{"id":4999,"date":"2025-06-17T13:10:15","date_gmt":"2025-06-17T13:10:15","guid":{"rendered":"https:\/\/kaizen-blog.org\/?p=4999"},"modified":"2025-06-17T13:10:18","modified_gmt":"2025-06-17T13:10:18","slug":"trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass","status":"publish","type":"post","link":"https:\/\/kaizen-blog.org\/en\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/","title":{"rendered":"Trump\u2019s Iran stance divides the MAGA movement - and the White House loses all restraint"},"content":{"rendered":"<p>It was a moment that laid bare the full political disarray of the United States. As Donald Trump sat aboard Air Force One, flying back from an abruptly ended G7 summit in Canada, the president was not speaking about diplomacy or security - but about Tucker Carlson. About Marjorie Taylor Greene. About Charlie Kirk. And about a governor whose state was mourning two murdered lawmakers. The world is on the brink of a new Middle East war. Yet at the center of American power, another drama is unfolding - the growing rift between Trump and his own loyalists. \u201cIRAN CAN NOT HAVE A NUCLEAR WEAPON!\u201d the president wrote in all caps on his social media platform - a direct response to Carlson, who had previously warned him not to betray his own base by launching another war in the Middle East.<\/p>\n\n\n\n<p>That the president is now clashing not only with the Democratic opposition but with his own base reveals a deeper erosion of his political compass. Trump\u2019s foreign policy calculus has long become a stage for national self-dramatization - regardless of the consequences. The criticism from within his own ranks shows that the once-unified MAGA movement is fracturing. While Carlson was still seen in 2020 as the mouthpiece of Trumpist conservatism, he is now publicly dismissed as \u201ckooky.\u201d Marjorie Taylor Greene and Charlie Kirk are also urging restraint - America must not once again become a pawn in global power struggles - but Trump reacts as always: petulantly, imperiously, and devoid of any sense of responsibility.<\/p>\n\n\n\n<p>The peak of tastelessness came when Trump was asked about the targeted killings of two lawmakers in Minnesota. Would he call the Democratic governor, Tim Walz? \u201cI\u2019m not calling him,\u201d Trump responded. \u201cHe\u2019s slick and whacked out. That would be a waste of time.\u201d Two dead, including a husband - but for the president of the United States, that is no reason for sympathy, only an opportunity for defamation. While the country wonders how it came to this, Trump is showing with chilling clarity how little political responsibility and empathy mean in his world. And what remains is what has long become the norm - a president who divides where he should unite - even when the nation is in mourning.<\/p>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"dark-america,topstory,trump-s-world\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1750165815\"\r\n\t            data-title=\"Trumps Iran-Kurs spaltet die MAGA-Bewegung \u2013 und das Wei\u00dfe Haus verliert jedes Ma\u00df\" \r\n\t            data-home=\"https:\/\/kaizen-blog.org\/en\/\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Es war ein Moment, der die ganze politische Schieflage der Vereinigten Staaten offenbarte. W\u00e4hrend Donald Trump an Bord der Air Force One sa\u00df, zur\u00fcckgeflogen aus einem abrupt abgebrochenen G7-Gipfel in Kanada, sprach der Pr\u00e4sident nicht \u00fcber Diplomatie, nicht \u00fcber Sicherheit \u2013 sondern \u00fcber Tucker Carlson. \u00dcber Marjorie Taylor Greene. \u00dcber Charlie Kirk. Und \u00fcber einen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5000,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[46,7,41],"tags":[],"class_list":["post-4999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dark-america","category-topstory","category-trump-s-world"],"featured_image_src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/rip.webp?fit=850%2C508&ssl=1","author_info":{"display_name":"Rainer Hofmann","author_link":"https:\/\/kaizen-blog.org\/en\/author\/admin\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trumps Iran-Kurs spaltet die MAGA-Bewegung \u2013 und das Wei\u00dfe Haus verliert jedes Ma\u00df - The Kaizen Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kaizen-blog.org\/en\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trumps Iran-Kurs spaltet die MAGA-Bewegung \u2013 und das Wei\u00dfe Haus verliert jedes Ma\u00df\" \/>\n<meta property=\"og:description\" content=\"Es war ein Moment, der die ganze politische Schieflage der Vereinigten Staaten offenbarte. W\u00e4hrend Donald Trump an Bord der Air Force One sa\u00df, zur\u00fcckgeflogen aus einem abrupt abgebrochenen G7-Gipfel in Kanada, sprach der Pr\u00e4sident nicht \u00fcber Diplomatie, nicht \u00fcber Sicherheit \u2013 sondern \u00fcber Tucker Carlson. \u00dcber Marjorie Taylor Greene. \u00dcber Charlie Kirk. Und \u00fcber einen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kaizen-blog.org\/en\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/\" \/>\n<meta property=\"og:site_name\" content=\"The Kaizen Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rainer.hofmann.2025\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-17T13:10:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-17T13:10:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/rip.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Rainer Hofmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rainer Hofmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\\\/\"},\"author\":{\"name\":\"Rainer Hofmann\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\"},\"headline\":\"Trumps Iran-Kurs spaltet die MAGA-Bewegung \u2013 und das Wei\u00dfe Haus verliert jedes Ma\u00df\",\"datePublished\":\"2025-06-17T13:10:15+00:00\",\"dateModified\":\"2025-06-17T13:10:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\\\/\"},\"wordCount\":385,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/rip.webp?fit=850%2C508&ssl=1\",\"articleSection\":[\"Dark America\",\"Topstory\",\"Trumpland\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/kaizen-blog.org\\\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\\\/\",\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\\\/\",\"name\":\"Trumps Iran-Kurs spaltet die MAGA-Bewegung \u2013 und das Wei\u00dfe Haus verliert jedes Ma\u00df - The Kaizen Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/rip.webp?fit=850%2C508&ssl=1\",\"datePublished\":\"2025-06-17T13:10:15+00:00\",\"dateModified\":\"2025-06-17T13:10:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kaizen-blog.org\\\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/rip.webp?fit=850%2C508&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/rip.webp?fit=850%2C508&ssl=1\",\"width\":850,\"height\":508},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/kaizen-blog.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trumps Iran-Kurs spaltet die MAGA-Bewegung \u2013 und das Wei\u00dfe Haus verliert jedes Ma\u00df\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#website\",\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/\",\"name\":\"The Kaizen Blog\",\"description\":\"Investigativer Journalismus\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kaizen-blog.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\",\"name\":\"Rainer Hofmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"caption\":\"Rainer Hofmann\"},\"sameAs\":[\"https:\\\/\\\/kaizen-blog.org\"],\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trumps Iran-Kurs spaltet die MAGA-Bewegung \u2013 und das Wei\u00dfe Haus verliert jedes Ma\u00df - The Kaizen Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kaizen-blog.org\/en\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/","og_locale":"en_US","og_type":"article","og_title":"Trumps Iran-Kurs spaltet die MAGA-Bewegung \u2013 und das Wei\u00dfe Haus verliert jedes Ma\u00df","og_description":"Es war ein Moment, der die ganze politische Schieflage der Vereinigten Staaten offenbarte. W\u00e4hrend Donald Trump an Bord der Air Force One sa\u00df, zur\u00fcckgeflogen aus einem abrupt abgebrochenen G7-Gipfel in Kanada, sprach der Pr\u00e4sident nicht \u00fcber Diplomatie, nicht \u00fcber Sicherheit \u2013 sondern \u00fcber Tucker Carlson. \u00dcber Marjorie Taylor Greene. \u00dcber Charlie Kirk. Und \u00fcber einen [&hellip;]","og_url":"https:\/\/kaizen-blog.org\/en\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/","og_site_name":"The Kaizen Blog","article_publisher":"https:\/\/www.facebook.com\/rainer.hofmann.2025\/","article_published_time":"2025-06-17T13:10:15+00:00","article_modified_time":"2025-06-17T13:10:18+00:00","og_image":[{"width":850,"height":508,"url":"https:\/\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/rip.webp","type":"image\/webp"}],"author":"Rainer Hofmann","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rainer Hofmann","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kaizen-blog.org\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/#article","isPartOf":{"@id":"https:\/\/kaizen-blog.org\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/"},"author":{"name":"Rainer Hofmann","@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0"},"headline":"Trumps Iran-Kurs spaltet die MAGA-Bewegung \u2013 und das Wei\u00dfe Haus verliert jedes Ma\u00df","datePublished":"2025-06-17T13:10:15+00:00","dateModified":"2025-06-17T13:10:18+00:00","mainEntityOfPage":{"@id":"https:\/\/kaizen-blog.org\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/"},"wordCount":385,"commentCount":0,"image":{"@id":"https:\/\/kaizen-blog.org\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/rip.webp?fit=850%2C508&ssl=1","articleSection":["Dark America","Topstory","Trumpland"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kaizen-blog.org\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kaizen-blog.org\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/","url":"https:\/\/kaizen-blog.org\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/","name":"Trumps Iran-Kurs spaltet die MAGA-Bewegung \u2013 und das Wei\u00dfe Haus verliert jedes Ma\u00df - The Kaizen Blog","isPartOf":{"@id":"https:\/\/kaizen-blog.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kaizen-blog.org\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/#primaryimage"},"image":{"@id":"https:\/\/kaizen-blog.org\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/rip.webp?fit=850%2C508&ssl=1","datePublished":"2025-06-17T13:10:15+00:00","dateModified":"2025-06-17T13:10:18+00:00","author":{"@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0"},"breadcrumb":{"@id":"https:\/\/kaizen-blog.org\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kaizen-blog.org\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kaizen-blog.org\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/#primaryimage","url":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/rip.webp?fit=850%2C508&ssl=1","contentUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/rip.webp?fit=850%2C508&ssl=1","width":850,"height":508},{"@type":"BreadcrumbList","@id":"https:\/\/kaizen-blog.org\/trumps-iran-kurs-spaltet-die-maga-bewegung-und-das-weisse-haus-verliert-jedes-mass\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kaizen-blog.org\/"},{"@type":"ListItem","position":2,"name":"Trumps Iran-Kurs spaltet die MAGA-Bewegung \u2013 und das Wei\u00dfe Haus verliert jedes Ma\u00df"}]},{"@type":"WebSite","@id":"https:\/\/kaizen-blog.org\/#website","url":"https:\/\/kaizen-blog.org\/","name":"The Kaizen Blog","description":"Investigative Journalism","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kaizen-blog.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0","name":"Rainer Hofmann","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","url":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","contentUrl":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","caption":"Rainer Hofmann"},"sameAs":["https:\/\/kaizen-blog.org"],"url":"https:\/\/kaizen-blog.org\/en\/author\/admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/rip.webp?fit=850%2C508&ssl=1","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":31224,"url":"https:\/\/kaizen-blog.org\/en\/10-maerz-2026-kurznachrichten\/","url_meta":{"origin":4999,"position":0},"title":"March 10, 2026 \u2013 Short News","author":"TEAM KAIZEN BLOG","date":"March 10, 2026","format":false,"excerpt":"Trump telefoniert mit Putin \u2013 Iran, Ukraine und der \u00d6lmarkt im selben Gespr\u00e4ch! Trump \u00fcber Russland: \u201eWir werden diese Sanktionen aufheben, bis sich die Lage wieder ordnet. Wer wei\u00df, vielleicht m\u00fcssen wir sie gar nicht wieder verh\u00e4ngen.\u201c - (Trump bezieht sich aber nur auf den Zusammenhang der Sanktionen, die den\u2026","rel":"","context":"In &quot;+++ Kaizen News Ticker +++&quot;","block_context":{"text":"+++ Kaizen News Ticker +++","link":"https:\/\/kaizen-blog.org\/en\/category\/ticker\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizenlive-2026-03-10T011434.038.webp?fit=905%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizenlive-2026-03-10T011434.038.webp?fit=905%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizenlive-2026-03-10T011434.038.webp?fit=905%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizenlive-2026-03-10T011434.038.webp?fit=905%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":33378,"url":"https:\/\/kaizen-blog.org\/en\/die-sechste-woche-trump-erklaert-den-sieg-und-der-krieg-erklaert-das-gegenteil\/","url_meta":{"origin":4999,"position":1},"title":"Week six - Trump declares victory, and the war declares the opposite","author":"Rainer Hofmann","date":"April 4, 2026","format":false,"excerpt":"Donald Trump stand am Mittwoch, dem 1. April, im Cross Hall des Weissen Hauses und sprach zur Nation. Es war seine erste Liveansprache seit Kriegsbeginn, f\u00fcnf Wochen nach dem ersten Einschlag. Er sagte, die USA h\u00e4tten Iran geschlagen und vollst\u00e4ndig dezimiert - milit\u00e4risch, wirtschaftlich, in jeder Hinsicht. Irans Radar sei\u2026","rel":"","context":"In &quot;Topstory&quot;","block_context":{"text":"Topstory","link":"https:\/\/kaizen-blog.org\/en\/category\/topstory\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/kaizennewsday-2026-04-04T161649.262.jpg?fit=905%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/kaizennewsday-2026-04-04T161649.262.jpg?fit=905%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/kaizennewsday-2026-04-04T161649.262.jpg?fit=905%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/kaizennewsday-2026-04-04T161649.262.jpg?fit=905%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31158,"url":"https:\/\/kaizen-blog.org\/en\/09-maerz-2026-kurznachrichten\/","url_meta":{"origin":4999,"position":2},"title":"March 9, 2026 \u2013 Short News","author":"TEAM KAIZEN BLOG","date":"March 9, 2026","format":false,"excerpt":"Machtwechsel unter Bomben \u2013 Mojtaba Khamenei \u00fcbernimmt in einem Land im Krieg! Mojtaba Chamenei Neun Tage nach Beginn der amerikanisch-israelischen Angriffe steht Iran vor einem radikalen Einschnitt. Ajatollah Ali Chamenei ist bei einem Luftangriff get\u00f6tet worden. In den fr\u00fchen Morgenstunden verk\u00fcndeten f\u00fchrende schiitische Geistliche nun seinen Nachfolger: Mojtaba Chamenei, 56\u2026","rel":"","context":"In &quot;+++ Kaizen News Ticker +++&quot;","block_context":{"text":"+++ Kaizen News Ticker +++","link":"https:\/\/kaizen-blog.org\/en\/category\/ticker\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizenlive-2026-03-09T021237.368.webp?fit=905%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizenlive-2026-03-09T021237.368.webp?fit=905%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizenlive-2026-03-09T021237.368.webp?fit=905%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizenlive-2026-03-09T021237.368.webp?fit=905%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":33531,"url":"https:\/\/kaizen-blog.org\/en\/iran-lehnt-ab-trump-will-das-oel-waffen-verschwunden-und-dienstag-steht-vor-der-tuer\/","url_meta":{"origin":4999,"position":3},"title":"Iran rejects. Trump wants the oil - weapons disappeared - and Tuesday is approaching","author":"TEAM KAIZEN BLOG","date":"April 6, 2026","format":false,"excerpt":"Iran hat den Waffenstillstandsvorschlag abgelehnt. Die Antwort ging \u00fcber Pakistan an Washington. Mojtaba Ferdousi Pour, Leiter der iranischen Diplomatenmission in Kairo, sagte es klar: Wir akzeptieren keinen blo\u00dfen Waffenstillstand. Wir akzeptieren nur ein Ende des Krieges mit Garantien, dass wir nicht erneut angegriffen werden. Der Vorschlag der \u00e4gyptisch-pakistanisch-t\u00fcrkischen Vermittler \u2013\u2026","rel":"","context":"In &quot;State News&quot;","block_context":{"text":"State News","link":"https:\/\/kaizen-blog.org\/en\/category\/state-news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/batch_kaizennewsday-2026-04-06T190120.784.webp?fit=905%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/batch_kaizennewsday-2026-04-06T190120.784.webp?fit=905%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/batch_kaizennewsday-2026-04-06T190120.784.webp?fit=905%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/batch_kaizennewsday-2026-04-06T190120.784.webp?fit=905%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":34750,"url":"https:\/\/kaizen-blog.org\/en\/23-april-2026-kurznachrichten\/","url_meta":{"origin":4999,"position":4},"title":"April 23, 2026 \u2013 Short News","author":"TEAM KAIZEN BLOG","date":"April 23, 2026","format":false,"excerpt":"Staatsbesuch ohne Begegnung \u2013 warum Charles den Kontakt zu Epstein-Opfern vermeidet! Die Reise steht fest, der Ablauf ist geplant, die Termine sind gesetzt. Wenn Charles III. kommende Woche in die Vereinigten Staaten reist, wird er empfangen, sprechen, repr\u00e4sentieren. Was nicht stattfinden wird, ist ein Treffen mit den Opfern von Jeffrey\u2026","rel":"","context":"In &quot;+++ Kaizen News Ticker +++&quot;","block_context":{"text":"+++ Kaizen News Ticker +++","link":"https:\/\/kaizen-blog.org\/en\/category\/ticker\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/kaizenlive-2026-04-23T021253.486.webp?fit=905%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/kaizenlive-2026-04-23T021253.486.webp?fit=905%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/kaizenlive-2026-04-23T021253.486.webp?fit=905%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/kaizenlive-2026-04-23T021253.486.webp?fit=905%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31444,"url":"https:\/\/kaizen-blog.org\/en\/iran-greift-nachbarn-an-der-golf-steht-still-millionen-fliehen\/","url_meta":{"origin":4999,"position":5},"title":"Iran Attacks Neighbors, the Gulf Falls Silent, Millions Flee","author":"Rainer Hofmann","date":"March 12, 2026","format":false,"excerpt":"Der Krieg im Nahen Osten ger\u00e4t zunehmend au\u00dfer Kontrolle. Irans oberster F\u00fchrer Mojtaba Chamenei meldete sich erstmals nach Beginn der Angriffe zu Wort und machte klar, dass die Attacken auf Staaten am Persischen Golf fortgesetzt werden sollen. W\u00e4hrend die K\u00e4mpfe eskalieren, melden internationale Organisationen bereits eine der gr\u00f6\u00dften Fluchtbewegungen der\u2026","rel":"","context":"In &quot;Iran War&quot;","block_context":{"text":"Iran War","link":"https:\/\/kaizen-blog.org\/en\/category\/investigativ\/iran-war\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-12T152024.774.webp?fit=905%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-12T152024.774.webp?fit=905%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-12T152024.774.webp?fit=905%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-12T152024.774.webp?fit=905%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts\/4999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/comments?post=4999"}],"version-history":[{"count":0,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts\/4999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/media\/5000"}],"wp:attachment":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/media?parent=4999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/categories?post=4999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/tags?post=4999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}