{"id":445,"date":"2025-02-18T11:50:45","date_gmt":"2025-02-18T11:50:45","guid":{"rendered":"https:\/\/kaizen-blog.org\/?p=445"},"modified":"2025-05-25T12:58:26","modified_gmt":"2025-05-25T12:58:26","slug":"wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection","status":"publish","type":"post","link":"https:\/\/kaizen-blog.org\/en\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/","title":{"rendered":"Election Broadcasts With Little Climate Protection"},"content":{"rendered":"<p>Election broadcasts go around in circles, but one topic is once again left behind. Migration, the economy, internal security these are the buzzwords that dominate every election broadcast. Climate and environment? At most a footnote, a convenient phrase quickly checked off before returning to the political skirmish.<\/p>\n\n\n\n<p>But this prioritization is not only shortsighted it is extremely dangerous. Without a functioning climate, without an intact environment, all other discussions are meaningless. What good are heated debates about the future of the economy if floods, droughts, and storms destroy entire regions? What is the point of endless arguments about migration if climate change will force millions of people to flee anyway?<\/p>\n\n\n\n<p>But what happens instead? Politicians lull themselves into the illusion that climate protection can be pushed aside with the current measures.<\/p>\n\n\n\n<p>And if this continues? Then we will no longer need to discuss migration or the economy.<\/p>\n\n\n\n<p>Then the issue will resolve itself because the world will remigrate the people.<\/p>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"planet-earth\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1739879445\"\r\n\t            data-title=\"Wahlsendungen fast ohne Klimaschutz\" \r\n\t            data-home=\"https:\/\/kaizen-blog.org\/en\/\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Die Wahlkampfsendungen drehen sich im Kreis, doch ein Thema bleibt wieder einmal auf der Strecke. Migration, Wirtschaft, innere Sicherheit \u2013 das sind die Schlagworte, die jede Wahlsendung dominieren. Klima und Umwelt? H\u00f6chstens eine Randnotiz, eine wohlfeile Floskel, die man schnell abhakt, bevor es wieder zur\u00fcck zum politischen Schlagabtausch geht. Doch diese Priorit\u00e4tensetzung ist nicht nur [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":446,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[37],"tags":[],"class_list":["post-445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-planet-earth"],"featured_image_src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/05\/clima-change-kaizen-blog.webp?fit=986%2C494&ssl=1","author_info":{"display_name":"Rainer Hofmann","author_link":"https:\/\/kaizen-blog.org\/en\/author\/admin\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wahlsendungen fast ohne Klimaschutz - The Kaizen Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kaizen-blog.org\/en\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wahlsendungen fast ohne Klimaschutz - The Kaizen Blog\" \/>\n<meta property=\"og:description\" content=\"Die Wahlkampfsendungen drehen sich im Kreis, doch ein Thema bleibt wieder einmal auf der Strecke. Migration, Wirtschaft, innere Sicherheit \u2013 das sind die Schlagworte, die jede Wahlsendung dominieren. Klima und Umwelt? H\u00f6chstens eine Randnotiz, eine wohlfeile Floskel, die man schnell abhakt, bevor es wieder zur\u00fcck zum politischen Schlagabtausch geht. Doch diese Priorit\u00e4tensetzung ist nicht nur [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kaizen-blog.org\/en\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/\" \/>\n<meta property=\"og:site_name\" content=\"The Kaizen Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rainer.hofmann.2025\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-18T11:50:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-25T12:58:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kaizen-blog.org\/wp-content\/uploads\/2025\/05\/clima-change-kaizen-blog.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"986\" \/>\n\t<meta property=\"og:image:height\" content=\"494\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Rainer Hofmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rainer Hofmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\\\/\"},\"author\":{\"name\":\"Rainer Hofmann\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\"},\"headline\":\"Wahlsendungen fast ohne Klimaschutz\",\"datePublished\":\"2025-02-18T11:50:45+00:00\",\"dateModified\":\"2025-05-25T12:58:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\\\/\"},\"wordCount\":168,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/clima-change-kaizen-blog.webp?fit=986%2C494&ssl=1\",\"articleSection\":[\"Planet Earth\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/kaizen-blog.org\\\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\\\/\",\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\\\/\",\"name\":\"Wahlsendungen fast ohne Klimaschutz - The Kaizen Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/clima-change-kaizen-blog.webp?fit=986%2C494&ssl=1\",\"datePublished\":\"2025-02-18T11:50:45+00:00\",\"dateModified\":\"2025-05-25T12:58:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kaizen-blog.org\\\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/clima-change-kaizen-blog.webp?fit=986%2C494&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/clima-change-kaizen-blog.webp?fit=986%2C494&ssl=1\",\"width\":986,\"height\":494},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/kaizen-blog.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wahlsendungen fast ohne Klimaschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#website\",\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/\",\"name\":\"The Kaizen Blog\",\"description\":\"Investigativer Journalismus\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kaizen-blog.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\",\"name\":\"Rainer Hofmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"caption\":\"Rainer Hofmann\"},\"sameAs\":[\"https:\\\/\\\/kaizen-blog.org\"],\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wahlsendungen fast ohne Klimaschutz - The Kaizen Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kaizen-blog.org\/en\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/","og_locale":"en_US","og_type":"article","og_title":"Wahlsendungen fast ohne Klimaschutz - The Kaizen Blog","og_description":"Die Wahlkampfsendungen drehen sich im Kreis, doch ein Thema bleibt wieder einmal auf der Strecke. Migration, Wirtschaft, innere Sicherheit \u2013 das sind die Schlagworte, die jede Wahlsendung dominieren. Klima und Umwelt? H\u00f6chstens eine Randnotiz, eine wohlfeile Floskel, die man schnell abhakt, bevor es wieder zur\u00fcck zum politischen Schlagabtausch geht. Doch diese Priorit\u00e4tensetzung ist nicht nur [&hellip;]","og_url":"https:\/\/kaizen-blog.org\/en\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/","og_site_name":"The Kaizen Blog","article_publisher":"https:\/\/www.facebook.com\/rainer.hofmann.2025\/","article_published_time":"2025-02-18T11:50:45+00:00","article_modified_time":"2025-05-25T12:58:26+00:00","og_image":[{"width":986,"height":494,"url":"https:\/\/kaizen-blog.org\/wp-content\/uploads\/2025\/05\/clima-change-kaizen-blog.webp","type":"image\/webp"}],"author":"Rainer Hofmann","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rainer Hofmann","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kaizen-blog.org\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/#article","isPartOf":{"@id":"https:\/\/kaizen-blog.org\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/"},"author":{"name":"Rainer Hofmann","@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0"},"headline":"Wahlsendungen fast ohne Klimaschutz","datePublished":"2025-02-18T11:50:45+00:00","dateModified":"2025-05-25T12:58:26+00:00","mainEntityOfPage":{"@id":"https:\/\/kaizen-blog.org\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/"},"wordCount":168,"commentCount":0,"image":{"@id":"https:\/\/kaizen-blog.org\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/05\/clima-change-kaizen-blog.webp?fit=986%2C494&ssl=1","articleSection":["Planet Earth"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kaizen-blog.org\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kaizen-blog.org\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/","url":"https:\/\/kaizen-blog.org\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/","name":"Wahlsendungen fast ohne Klimaschutz - The Kaizen Blog","isPartOf":{"@id":"https:\/\/kaizen-blog.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kaizen-blog.org\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/#primaryimage"},"image":{"@id":"https:\/\/kaizen-blog.org\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/05\/clima-change-kaizen-blog.webp?fit=986%2C494&ssl=1","datePublished":"2025-02-18T11:50:45+00:00","dateModified":"2025-05-25T12:58:26+00:00","author":{"@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0"},"breadcrumb":{"@id":"https:\/\/kaizen-blog.org\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kaizen-blog.org\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kaizen-blog.org\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/#primaryimage","url":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/05\/clima-change-kaizen-blog.webp?fit=986%2C494&ssl=1","contentUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/05\/clima-change-kaizen-blog.webp?fit=986%2C494&ssl=1","width":986,"height":494},{"@type":"BreadcrumbList","@id":"https:\/\/kaizen-blog.org\/wahlsendungen-fast-ohne-klimaschutz-election-broadcasts-with-little-climate-protection\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kaizen-blog.org\/"},{"@type":"ListItem","position":2,"name":"Wahlsendungen fast ohne Klimaschutz"}]},{"@type":"WebSite","@id":"https:\/\/kaizen-blog.org\/#website","url":"https:\/\/kaizen-blog.org\/","name":"The Kaizen Blog","description":"Investigative Journalism","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kaizen-blog.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0","name":"Rainer Hofmann","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","url":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","contentUrl":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","caption":"Rainer Hofmann"},"sameAs":["https:\/\/kaizen-blog.org"],"url":"https:\/\/kaizen-blog.org\/en\/author\/admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/05\/clima-change-kaizen-blog.webp?fit=986%2C494&ssl=1","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":12736,"url":"https:\/\/kaizen-blog.org\/en\/projekt-2025-trumps-masterplan-zur-zerstoerung-des-planeten\/","url_meta":{"origin":445,"position":0},"title":"Project 2025 \u2013 Trump\u2019s Masterplan for the Destruction of the Planet","author":"Rainer Hofmann","date":"August 21, 2025","format":false,"excerpt":"Wochenlange Recherchen haben ein ersch\u00fctterndes Bild zutage gef\u00f6rdert, das in seiner Tragweite selbst pessimistische Prognosen \u00fcbertrifft. Die Vereinigten Staaten erleben unter der zweiten Trump-Administration eine beispiellose Umkehrung jahrzehntelanger Umweltschutzpolitik, deren Auswirkungen weit \u00fcber die amerikanischen Grenzen hinausreichen und die globalen Bem\u00fchungen zur Bew\u00e4ltigung der Klimakrise fundamental untergraben. Was sich seit\u2026","rel":"","context":"In &quot;Planet Earth&quot;","block_context":{"text":"Planet Earth","link":"https:\/\/kaizen-blog.org\/en\/category\/planet-earth\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/08\/Kopie-von-Kopie-von-Kopie-von-The-Kaizen-Blog-Online-Magazin56.webp?fit=900%2C508&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/08\/Kopie-von-Kopie-von-Kopie-von-The-Kaizen-Blog-Online-Magazin56.webp?fit=900%2C508&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/08\/Kopie-von-Kopie-von-Kopie-von-The-Kaizen-Blog-Online-Magazin56.webp?fit=900%2C508&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/08\/Kopie-von-Kopie-von-Kopie-von-The-Kaizen-Blog-Online-Magazin56.webp?fit=900%2C508&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3547,"url":"https:\/\/kaizen-blog.org\/en\/weidel-bitte-hoer-auf-zu-luegen-es-nervt\/","url_meta":{"origin":445,"position":1},"title":"\u201cWeidel, please stop lying \u2013 it\u2019s annoying\u201d","author":"Rainer Hofmann","date":"June 8, 2025","format":false,"excerpt":"Ein Artikel \u00fcber hei\u00dfe Luft, kalte Fakten und die politische Kunst des Z\u00fcndelns. Es war einer dieser Tage, an denen man sich w\u00fcnscht, die Politik w\u00fcrde wenigstens ab und zu den Unterschied zwischen Skandal und Schlagwort kennen. Am 7. Juni 2025 verbreitete Alice Weidel \u00fcber X (ehemals Twitter) die Behauptung,\u2026","rel":"","context":"In &quot;AFD - \"No Thanks\"&quot;","block_context":{"text":"AFD - \"No Thanks\"","link":"https:\/\/kaizen-blog.org\/en\/category\/afd-no-thanks\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/weidel-clima.webp?fit=850%2C508&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/weidel-clima.webp?fit=850%2C508&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/weidel-clima.webp?fit=850%2C508&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/weidel-clima.webp?fit=850%2C508&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":10524,"url":"https:\/\/kaizen-blog.org\/en\/amerikas-klimaschutz-am-scheideweg-trumps-radikaler-kurs-und-globale-spannungen\/","url_meta":{"origin":445,"position":2},"title":"America's Climate Policy at a Crossroads - Trump's Radical Course and Global Tensions","author":"Rainer Hofmann","date":"July 29, 2025","format":false,"excerpt":"Die Regierung von US-Pr\u00e4sident Donald Trump hat am Dienstag angek\u00fcndigt, einen zentralen wissenschaftlichen Grundpfeiler der amerikanischen Klimapolitik aufheben zu wollen \u2013 eine Entscheidung, die weitreichende Konsequenzen f\u00fcr den Umwelt- und Gesundheitsschutz h\u00e4tte. Konkret geht es um die sogenannte \u201eEndangerment Finding\u201c, eine bereits 2009 erfolgte offizielle Feststellung der US-Umweltbeh\u00f6rde EPA, wonach\u2026","rel":"","context":"In &quot;Planet Earth&quot;","block_context":{"text":"Planet Earth","link":"https:\/\/kaizen-blog.org\/en\/category\/planet-earth\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/07\/Social-Kaizen155.webp?fit=900%2C508&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/07\/Social-Kaizen155.webp?fit=900%2C508&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/07\/Social-Kaizen155.webp?fit=900%2C508&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/07\/Social-Kaizen155.webp?fit=900%2C508&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2635,"url":"https:\/\/kaizen-blog.org\/en\/das-kabinett-das-die-welt-in-atem-haelt-ein-spiegelbild-der-afd\/","url_meta":{"origin":445,"position":3},"title":"The Cabinet That Keeps the World on Edge \u2013 A Mirror Image of the AfD","author":"Rainer Hofmann","date":"March 30, 2025","format":false,"excerpt":"Hier begegnen Sie den K\u00f6pfen hinter der Trump-Regierung \u2013 einem Kabinett, das nicht nur die politische Landschaft der USA pr\u00e4gt, sondern weit \u00fcber die Grenzen hinaus wirkt. Ministerinnen und Minister, die mit radikalen Positionen, ideologischer Entschlossenheit und unverhohlener Verachtung gegen\u00fcber liberalen Errungenschaften auftreten. Was auff\u00e4llt: Viele Namen, viele Gesichter \u2013\u2026","rel":"","context":"In &quot;Documentation&quot;","block_context":{"text":"Documentation","link":"https:\/\/kaizen-blog.org\/en\/category\/documentation\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/USA-Kabinett.webp?fit=900%2C508&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/USA-Kabinett.webp?fit=900%2C508&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/USA-Kabinett.webp?fit=900%2C508&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/USA-Kabinett.webp?fit=900%2C508&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":11697,"url":"https:\/\/kaizen-blog.org\/en\/exportmodell-der-kontrolle-wie-trumps-politisches-drehbuch-die-forschung-knebelt-und-europas-demokratien-bedroht\/","url_meta":{"origin":445,"position":4},"title":"Export Model of Control \u2013 How Trump's Political Playbook Muzzles Research and Threatens Europe's Democracies","author":"Rainer Hofmann","date":"August 9, 2025","format":false,"excerpt":"Unsere Arbeit versteht sich nicht nur als Analyse amerikanischer Innenpolitik, sondern als Fr\u00fchwarnsystem f\u00fcr die Demokratie diesseits des Atlantiks. Wenn wir dokumentieren, wie in den USA Forschungsfreiheit ausgeschaltet, Klimawissenschaft delegitimiert und \u00f6ffentliche Gelder an politische Loyalit\u00e4t gekn\u00fcpft werden, ...","rel":"","context":"In &quot;Topstory&quot;","block_context":{"text":"Topstory","link":"https:\/\/kaizen-blog.org\/en\/category\/topstory\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/08\/The-Kaizen-Blog-Online-Magazin185.webp?fit=900%2C508&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/08\/The-Kaizen-Blog-Online-Magazin185.webp?fit=900%2C508&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/08\/The-Kaizen-Blog-Online-Magazin185.webp?fit=900%2C508&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/08\/The-Kaizen-Blog-Online-Magazin185.webp?fit=900%2C508&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2873,"url":"https:\/\/kaizen-blog.org\/en\/zwischen-pipeline-und-protest-wie-trumps-neue-umweltpolitik-alaska-verheizt\/","url_meta":{"origin":445,"position":5},"title":"Between Pipeline and Protest - How Trump's New Environmental Policy Is Burning Alaska","author":"Rainer Hofmann","date":"June 4, 2025","format":false,"excerpt":"Es beginnt mit einem Bild aus dem Lehrbuch fossiler Machtpolitik: Ein Regierungsflieger landet auf dem arktischen Rollfeld von Prudhoe Bay. Neben ihm ragt die trans-Alaska-\u00d6lpipeline aus dem Boden \u2013 eine rostende Stahlader, Sinnbild f\u00fcr ein Amerika, das sich weigert, aus der Vergangenheit zu lernen. Innenminister Doug Burgum, Energieminister Chris Wright\u2026","rel":"","context":"In &quot;Planet Earth&quot;","block_context":{"text":"Planet Earth","link":"https:\/\/kaizen-blog.org\/en\/category\/planet-earth\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/alaska-is-not-for-sale.webp?fit=982%2C502&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/alaska-is-not-for-sale.webp?fit=982%2C502&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/alaska-is-not-for-sale.webp?fit=982%2C502&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/alaska-is-not-for-sale.webp?fit=982%2C502&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts\/445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/comments?post=445"}],"version-history":[{"count":0,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts\/445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/media\/446"}],"wp:attachment":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/media?parent=445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/categories?post=445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/tags?post=445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}