{"id":32319,"date":"2026-03-21T08:34:54","date_gmt":"2026-03-21T07:34:54","guid":{"rendered":"https:\/\/kaizen-blog.org\/?p=32319"},"modified":"2026-03-21T08:49:11","modified_gmt":"2026-03-21T07:49:11","slug":"der-mann-der-deutschland-seit-1813-vermisst-hat","status":"publish","type":"post","link":"https:\/\/kaizen-blog.org\/en\/der-mann-der-deutschland-seit-1813-vermisst-hat\/","title":{"rendered":"The man Germany has been missing since 1813"},"content":{"rendered":"<p>Maximilian Krah has spoken.<\/p>\n\n\n\n<p>Trump offers Germany more than it has received since 1813. Anyone who does not recognize that is stupid. Anyone who rejects it is anti German. The political elite is both. It must be replaced. You read that twice. Not because it is complex. But to make sure you understood it correctly.<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"117\" src=\"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_Kaizensatire-1.webp?resize=640%2C117&#038;ssl=1\" alt=\"\" class=\"wp-image-32321\" srcset=\"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_Kaizensatire-1.webp?w=905&amp;ssl=1 905w, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_Kaizensatire-1.webp?resize=18%2C3&amp;ssl=1 18w, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_Kaizensatire-1.webp?resize=300%2C55&amp;ssl=1 300w, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_Kaizensatire-1.webp?resize=768%2C140&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>You understood it correctly.<\/strong><\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>1813<\/strong><\/p>\n\n\n\n<p>Krah greift ins Regal und zieht ein Jahr heraus, in dem Napoleon auf dem R\u00fcckzug war und deutsche F\u00fcrsten die Seiten wechselten. Ein Jahr, in dem es kein Deutschland gab, keinen deutschen Staat, keine deutsche Verfassung \u2013 nur Territorien, Dynastien und die Frage, wessen Armee gerade durch welches Dorf marschiert. Dieses Jahr w\u00e4hlt ein gew\u00e4hlter Abgeordneter des Deutschen Bundestages als Vergleichspunkt f\u00fcr das Angebot eines amerikanischen Pr\u00e4sidenten im Jahr 2026.. Was genau Trump anbietet, erw\u00e4hnt Krah nicht. Das w\u00e4re auch schwierig, denn Trump hat Deutschland zuletzt Z\u00f6lle, Drohungen und die Aufforderung angeboten, mehr Geld f\u00fcr Waffen auszugeben. Vielleicht ist das seit 1813 tats\u00e4chlich das Gro\u00dfz\u00fcgigste, was jemand angeboten hat. Man m\u00fcsste die Zwischenjahre genauer pr\u00fcfen<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>1813<\/strong><\/p>\n\n\n\n<p><strong>And then the word. Anti German.<\/strong><\/p>\n\n\n\n<p>It sits there, in the middle of the sentence, as if it were the most normal thing in the world. As if a member of the Bundestag had not just labeled everyone who views Trump\u2019s policy toward Germany with skepticism using a term that German history has deliberately placed into certain compartments. Anti German. Anyone who rejects Trump is against Germany. Anyone who is against Germany must be replaced.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>The logic is complete. That is what is unsettling about it.<\/strong><\/p>\n\n\n\n<p>Krah sits in the Bundestag. He was elected. He does not write these sentences in secret, not as a provocation, not as a question - but as a statement. Calm. Convinced. With an exclamation mark at the end, the only sign of temperament in a text that otherwise radiates the composure of a man to whom his own conclusion appears entirely self evident.<\/p>\n\n\n\n<p><strong>Germany deserves this opportunity.<\/strong><\/p>\n\n\n\n<p>What opportunity. The opportunity to be grateful to an American president who wants to buy Greenland, annex Canada and publicly calls European allies cowards. That opportunity. The greatest since 1813. You sit in front of this sentence and feel something that is difficult to name. Not anger. More the quiet astonishment of someone watching a person walk in the wrong direction with complete conviction while explaining that everyone else has lost their way.<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"354\" src=\"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-21T082922.735.webp?resize=640%2C354&#038;ssl=1\" alt=\"\" class=\"wp-image-32320\" srcset=\"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-21T082922.735.webp?w=905&amp;ssl=1 905w, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-21T082922.735.webp?resize=18%2C10&amp;ssl=1 18w, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-21T082922.735.webp?resize=300%2C166&amp;ssl=1 300w, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-21T082922.735.webp?resize=768%2C424&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>There are people who do not bend reality. Who live in it, honestly and without detours. Krah is not one of them. He lives in a different reality, one in which 1813 was yesterday, in which Trump is a gift and in which the German political elite must be replaced because it does not accept this gift. In that reality, everything makes sense. That is the real problem.<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"kz-ad-root\">\n<style>\n@import url('https:\/\/fonts.googleapis.com\/css2?family=Bebas+Neue&family=Source+Sans+3:ital,wght@0,400;0,700;1,400&display=swap');\n\n.kz-ad-root { margin: 28px 0; }\n\n.kz-ad {\n  font-family: 'Source Sans 3', 'Segoe UI', Arial, sans-serif;\n  background: #ffffff;\n  border: 1px solid #DEDEDE;\n  border-radius: 4px;\n  overflow: hidden;\n  max-width: 100%;\n  box-sizing: border-box;\n}\n\n.kz-top {\n  background: #111111;\n  padding: 12px 18px;\n  display: flex;\n  align-items: center;\n  gap: 10px;\n}\n\n.kz-eyebrow-line {\n  width: 22px;\n  height: 2px;\n  background: #7A1A24;\n  flex-shrink: 0;\n}\n\n.kz-badge {\n  font-size: 13px;\n  font-weight: 700;\n  letter-spacing: 0.14em;\n  text-transform: uppercase;\n  color: #ffffff;\n}\n\n.kz-inner {\n  padding: 22px 18px 20px;\n}\n\n.kz-headline {\n  font-family: 'Bebas Neue', Impact, Arial Narrow, sans-serif;\n  font-size: 2.4rem;\n  font-weight: 400;\n  color: #111111;\n  line-height: 1.1;\n  margin: 0 0 16px 0;\n  letter-spacing: 0.03em;\n}\n\n.kz-headline span {\n  color: #8A8A8A;\n}\n\n.kz-text {\n  font-size: 1.05rem;\n  line-height: 1.75;\n  color: #333333;\n  margin: 0 0 16px 0;\n}\n\n.kz-callout {\n  font-size: 1.05rem;\n  line-height: 1.65;\n  color: #111111;\n  font-weight: 700;\n  border-left: 3px solid #7A1A24;\n  padding: 12px 14px;\n  margin: 0 0 22px 0;\n  background: #F7F7F7;\n  border-radius: 0 2px 2px 0;\n}\n\n.kz-btn {\n  display: flex;\n  align-items: center;\n  justify-content: center;\n  gap: 9px;\n  width: 100%;\n  box-sizing: border-box;\n  padding: 16px 20px;\n  background: #7A1A24;\n  color: #ffffff;\n  font-family: 'Source Sans 3', sans-serif;\n  font-weight: 700;\n  font-size: 1.1rem;\n  text-decoration: none;\n  border-radius: 2px;\n  transition: background 0.18s, transform 0.15s;\n  letter-spacing: 0.03em;\n  text-transform: uppercase;\n  margin-bottom: 16px;\n}\n\n.kz-btn:hover {\n  background: #5C1219;\n  transform: translateY(-1px);\n}\n\n.kz-btn svg { transition: transform 0.18s; }\n.kz-btn:hover svg { transform: translateX(3px); }\n\n.kz-footer {\n  display: flex;\n  align-items: center;\n  justify-content: center;\n  padding-bottom: 2px;\n}\n\n.kz-more {\n  font-size: 1.05rem;\n  color: #444444;\n  text-decoration: none;\n  transition: color 0.15s, border-color 0.15s;\n  font-style: italic;\n  border-bottom: 1px solid #CCCCCC;\n  padding-bottom: 2px;\n}\n\n.kz-more:hover { color: #7A1A24; border-color: #7A1A24; }\n\n@media (min-width: 540px) {\n  .kz-inner { padding: 24px 26px 22px; }\n  .kz-headline { font-size: 2.8rem; }\n\n  .kz-btn {\n    width: auto;\n    display: inline-flex;\n    padding: 15px 36px;\n  }\n\n  .kz-btn-wrap {\n    display: flex;\n    align-items: center;\n    justify-content: space-between;\n    gap: 16px;\n  }\n\n  .kz-footer {\n    justify-content: flex-end;\n  }\n}\n<\/style>\n\n<div class=\"kz-ad\">\n  <div class=\"kz-top\">\n    <div class=\"kz-eyebrow-line\"><\/div>\n    <span class=\"kz-badge\">Independent Journalism \u00b7 Kaizen Blog<\/span>\n  <\/div>\n  <div class=\"kz-inner\">\n\n    <h3 class=\"kz-headline\">We are where,<br>it hurts. <span>wehtut.<\/span><\/h3>\n\n    <p class=\"kz-text\">We do not sit in comfort writing about the world - and we do not stop once the writing ends. Our help goes where it is needed. We are a small team. No investors, no millionaires, no large newsroom behind us. What we have is heart, determination, and the commitment to uncover things that others often overlook. If you want this work to continue, please support the Kaizen Blog.<\/p>\n\n    <div class=\"kz-callout\">Our work depends on those who pay attention - and stand up for making sure it remains possible.<\/div>\n\n    <div class=\"kz-btn-wrap\">\n      <a class=\"kz-btn\" href=\"https:\/\/buy.stripe.com\/14A4gzgJWaWm3gM1Ls3VC00\" target=\"_blank\" rel=\"noopener\">\n        Support our work\n        <svg width=\"17\" height=\"17\" viewbox=\"0 0 14 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n          <path d=\"M2 7h10M8 3l4 4-4 4\" stroke=\"#fff\" stroke-width=\"1.8\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n        <\/svg>\n      <\/a>\n      <div class=\"kz-footer\">\n        <a class=\"kz-more\" href=\"https:\/\/kaizen-blog.org\/en\/unterstuetzen-sie-unser-arbeit\/\" target=\"_blank\" rel=\"noopener\">About our work \u2192<\/a>\n      <\/div>\n    <\/div>\n\n  <\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"kb-news-update-box\" style=\"    max-width: 650px;    margin: 2rem auto;    padding: 1.25rem 1.5rem;    border-radius: 12px;    border: 1px solid rgba(120,120,120,0.4);    background: rgba(15,15,20,0.03);    backdrop-filter: blur(4px);    font-family: system-ui, -apple-system, BlinkMacSystemFont, 'Segoe UI', sans-serif;\">\n  <style>\n    @media (prefers-color-scheme: dark) {\n      .kb-news-update-box {\n        background: rgba(15,15,20,0.9) !important;\n        border-color: rgba(160,160,160,0.4) !important;\n      }\n      .kb-news-update-box h3 {\n        color: #f5f5f5 !important;\n      }\n      .kb-news-update-box p {\n        color: #e0e0e0 !important;\n      }\n      .kb-news-update-box a.kb-news-link {\n        color: #ffb347 !important;\n        border-color: rgba(255,179,71,0.4) !important;\n      }\n      .kb-news-update-box a.kb-news-link:hover {\n        background: rgba(255,179,71,0.12) !important;\n      }\n    }\n  <\/style>\n\n  <h3 style=\"      margin: 0 0 0.5rem 0;      font-size: 1.15rem;      letter-spacing: 0.02em;      text-transform: uppercase;  \">\n    Updates \u2013 Kaizen News Brief\n  <\/h3>\n\n  <p style=\"      margin: 0 0 0.9rem 0;      font-size: 0.95rem;      line-height: 1.5;  \">\n    All current curated daily updates can be found in the Kaizen News Brief. \n  <\/p>\n\n  <!-- Deutscher Button -->\n  <a class=\"kb-news-link\" href=\"https:\/\/kaizen-blog.org\/en\/21-m\u00e4rz-2026-kurznachrichten\/\" style=\"      display: inline-flex;      align-items: center;      gap: 0.4rem;      padding: 0.45rem 0.9rem;      border-radius: 999px;      border: 1px solid rgba(0,0,0,0.12);      font-size: 0.9rem;      text-decoration: none;      color: #004b8d;      transition: background 0.15s ease, transform 0.1s ease, border-color 0.15s ease;      margin-bottom: 0.5rem;      margin-right: 0.4rem;  \">\n    <span style=\"font-weight: 600;\">To the Kaizen News Brief<\/span>\n    <span aria-hidden=\"true\" style=\"font-size: 1.1rem;\">\u2197<\/span>\n  <\/a>\n\n  <!-- Englischer Button -->\n  <a class=\"kb-news-link\" href=\"https:\/\/kaizen-blog.org\/en\/21-m\u00e4rz-2026-kurznachrichten\/\" style=\"      display: inline-flex;      align-items: center;      gap: 0.4rem;      padding: 0.45rem 0.9rem;      border-radius: 999px;      border: 1px solid rgba(0,0,0,0.12);      font-size: 0.9rem;      text-decoration: none;      color: #004b8d;      transition: background 0.15s ease, transform 0.1s ease, border-color 0.15s ease;  \">\n    <span style=\"font-weight: 600;\">In English<\/span>\n    <span aria-hidden=\"true\" style=\"font-size: 1.1rem;\">\u2197<\/span>\n  <\/a>\n\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"news,satire,topstory\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1774082094\"\r\n\t            data-title=\"Der Mann, der Deutschland seit 1813 vermisst hat\" \r\n\t            data-home=\"https:\/\/kaizen-blog.org\/en\/\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Maximilian Krah has spoken. Trump offers Germany more than it has received since 1813. Anyone who does not recognize that is stupid. Anyone who rejects it is anti German. The political elite is both. It must be replaced. You read that twice. Not because it is complex.<\/p>","protected":false},"author":1,"featured_media":32320,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5,44,7],"tags":[],"class_list":["post-32319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-satire","category-topstory"],"featured_image_src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-21T082922.735.webp?fit=905%2C500&ssl=1","author_info":{"display_name":"Rainer Hofmann","author_link":"https:\/\/kaizen-blog.org\/en\/author\/admin\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der Mann, der Deutschland seit 1813 vermisst hat - The Kaizen Blog<\/title>\n<meta name=\"description\" content=\"Maximilian Krah hat gesprochen. Trump biete Deutschland mehr, als es seit 1813 bekommen habe. Wer das nicht erkenne, sei dumm. Wer es ablehne, sei anti-deutsch. Die politische Elite sei beides. Sie m\u00fcsse ersetzt werden.Man liest das zweimal. Nicht weil es komplex ist. Sondern weil man sichergehen will, dass man es richtig verstanden hat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kaizen-blog.org\/en\/der-mann-der-deutschland-seit-1813-vermisst-hat\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Mann, der Deutschland seit 1813 vermisst hat\" \/>\n<meta property=\"og:description\" content=\"Maximilian Krah hat gesprochen. Trump biete Deutschland mehr, als es seit 1813 bekommen habe. Wer das nicht erkenne, sei dumm. Wer es ablehne, sei anti-deutsch. Die politische Elite sei beides. Sie m\u00fcsse ersetzt werden.Man liest das zweimal. Nicht weil es komplex ist. Sondern weil man sichergehen will, dass man es richtig verstanden hat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kaizen-blog.org\/en\/der-mann-der-deutschland-seit-1813-vermisst-hat\/\" \/>\n<meta property=\"og:site_name\" content=\"The Kaizen Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rainer.hofmann.2025\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-21T07:34:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-21T07:49:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-21T082922.735.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"905\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Rainer Hofmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rainer Hofmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/der-mann-der-deutschland-seit-1813-vermisst-hat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/der-mann-der-deutschland-seit-1813-vermisst-hat\\\/\"},\"author\":{\"name\":\"Rainer Hofmann\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\"},\"headline\":\"Der Mann, der Deutschland seit 1813 vermisst hat\",\"datePublished\":\"2026-03-21T07:34:54+00:00\",\"dateModified\":\"2026-03-21T07:49:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/der-mann-der-deutschland-seit-1813-vermisst-hat\\\/\"},\"wordCount\":600,\"commentCount\":17,\"image\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/der-mann-der-deutschland-seit-1813-vermisst-hat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/batch_kaizennewsday-2026-03-21T082922.735.webp?fit=905%2C500&ssl=1\",\"articleSection\":[\"NEWS\",\"Satire &amp; Hell\",\"Topstory\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/kaizen-blog.org\\\/der-mann-der-deutschland-seit-1813-vermisst-hat\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/der-mann-der-deutschland-seit-1813-vermisst-hat\\\/\",\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/der-mann-der-deutschland-seit-1813-vermisst-hat\\\/\",\"name\":\"Der Mann, der Deutschland seit 1813 vermisst hat - The Kaizen Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/der-mann-der-deutschland-seit-1813-vermisst-hat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/der-mann-der-deutschland-seit-1813-vermisst-hat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/batch_kaizennewsday-2026-03-21T082922.735.webp?fit=905%2C500&ssl=1\",\"datePublished\":\"2026-03-21T07:34:54+00:00\",\"dateModified\":\"2026-03-21T07:49:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\"},\"description\":\"Maximilian Krah hat gesprochen. Trump biete Deutschland mehr, als es seit 1813 bekommen habe. Wer das nicht erkenne, sei dumm. Wer es ablehne, sei anti-deutsch. Die politische Elite sei beides. Sie m\u00fcsse ersetzt werden.Man liest das zweimal. Nicht weil es komplex ist. Sondern weil man sichergehen will, dass man es richtig verstanden hat.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/der-mann-der-deutschland-seit-1813-vermisst-hat\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kaizen-blog.org\\\/der-mann-der-deutschland-seit-1813-vermisst-hat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/der-mann-der-deutschland-seit-1813-vermisst-hat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/batch_kaizennewsday-2026-03-21T082922.735.webp?fit=905%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/batch_kaizennewsday-2026-03-21T082922.735.webp?fit=905%2C500&ssl=1\",\"width\":905,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/der-mann-der-deutschland-seit-1813-vermisst-hat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/kaizen-blog.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Mann, der Deutschland seit 1813 vermisst hat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#website\",\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/\",\"name\":\"The Kaizen Blog\",\"description\":\"Investigativer Journalismus\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kaizen-blog.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\",\"name\":\"Rainer Hofmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"caption\":\"Rainer Hofmann\"},\"sameAs\":[\"https:\\\/\\\/kaizen-blog.org\"],\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Mann, der Deutschland seit 1813 vermisst hat - The Kaizen Blog","description":"Maximilian Krah hat gesprochen. Trump biete Deutschland mehr, als es seit 1813 bekommen habe. Wer das nicht erkenne, sei dumm. Wer es ablehne, sei anti-deutsch. Die politische Elite sei beides. Sie m\u00fcsse ersetzt werden.Man liest das zweimal. Nicht weil es komplex ist. Sondern weil man sichergehen will, dass man es richtig verstanden hat.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kaizen-blog.org\/en\/der-mann-der-deutschland-seit-1813-vermisst-hat\/","og_locale":"en_US","og_type":"article","og_title":"Der Mann, der Deutschland seit 1813 vermisst hat","og_description":"Maximilian Krah hat gesprochen. Trump biete Deutschland mehr, als es seit 1813 bekommen habe. Wer das nicht erkenne, sei dumm. Wer es ablehne, sei anti-deutsch. Die politische Elite sei beides. Sie m\u00fcsse ersetzt werden.Man liest das zweimal. Nicht weil es komplex ist. Sondern weil man sichergehen will, dass man es richtig verstanden hat.","og_url":"https:\/\/kaizen-blog.org\/en\/der-mann-der-deutschland-seit-1813-vermisst-hat\/","og_site_name":"The Kaizen Blog","article_publisher":"https:\/\/www.facebook.com\/rainer.hofmann.2025\/","article_published_time":"2026-03-21T07:34:54+00:00","article_modified_time":"2026-03-21T07:49:11+00:00","og_image":[{"width":905,"height":500,"url":"https:\/\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-21T082922.735.webp","type":"image\/webp"}],"author":"Rainer Hofmann","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rainer Hofmann","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kaizen-blog.org\/der-mann-der-deutschland-seit-1813-vermisst-hat\/#article","isPartOf":{"@id":"https:\/\/kaizen-blog.org\/der-mann-der-deutschland-seit-1813-vermisst-hat\/"},"author":{"name":"Rainer Hofmann","@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0"},"headline":"Der Mann, der Deutschland seit 1813 vermisst hat","datePublished":"2026-03-21T07:34:54+00:00","dateModified":"2026-03-21T07:49:11+00:00","mainEntityOfPage":{"@id":"https:\/\/kaizen-blog.org\/der-mann-der-deutschland-seit-1813-vermisst-hat\/"},"wordCount":600,"commentCount":17,"image":{"@id":"https:\/\/kaizen-blog.org\/der-mann-der-deutschland-seit-1813-vermisst-hat\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-21T082922.735.webp?fit=905%2C500&ssl=1","articleSection":["NEWS","Satire &amp; Hell","Topstory"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kaizen-blog.org\/der-mann-der-deutschland-seit-1813-vermisst-hat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kaizen-blog.org\/der-mann-der-deutschland-seit-1813-vermisst-hat\/","url":"https:\/\/kaizen-blog.org\/der-mann-der-deutschland-seit-1813-vermisst-hat\/","name":"Der Mann, der Deutschland seit 1813 vermisst hat - The Kaizen Blog","isPartOf":{"@id":"https:\/\/kaizen-blog.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kaizen-blog.org\/der-mann-der-deutschland-seit-1813-vermisst-hat\/#primaryimage"},"image":{"@id":"https:\/\/kaizen-blog.org\/der-mann-der-deutschland-seit-1813-vermisst-hat\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-21T082922.735.webp?fit=905%2C500&ssl=1","datePublished":"2026-03-21T07:34:54+00:00","dateModified":"2026-03-21T07:49:11+00:00","author":{"@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0"},"description":"Maximilian Krah hat gesprochen. Trump biete Deutschland mehr, als es seit 1813 bekommen habe. Wer das nicht erkenne, sei dumm. Wer es ablehne, sei anti-deutsch. Die politische Elite sei beides. Sie m\u00fcsse ersetzt werden.Man liest das zweimal. Nicht weil es komplex ist. Sondern weil man sichergehen will, dass man es richtig verstanden hat.","breadcrumb":{"@id":"https:\/\/kaizen-blog.org\/der-mann-der-deutschland-seit-1813-vermisst-hat\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kaizen-blog.org\/der-mann-der-deutschland-seit-1813-vermisst-hat\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kaizen-blog.org\/der-mann-der-deutschland-seit-1813-vermisst-hat\/#primaryimage","url":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-21T082922.735.webp?fit=905%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-21T082922.735.webp?fit=905%2C500&ssl=1","width":905,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/kaizen-blog.org\/der-mann-der-deutschland-seit-1813-vermisst-hat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kaizen-blog.org\/"},{"@type":"ListItem","position":2,"name":"Der Mann, der Deutschland seit 1813 vermisst hat"}]},{"@type":"WebSite","@id":"https:\/\/kaizen-blog.org\/#website","url":"https:\/\/kaizen-blog.org\/","name":"The Kaizen Blog","description":"Investigative Journalism","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kaizen-blog.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0","name":"Rainer Hofmann","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","url":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","contentUrl":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","caption":"Rainer Hofmann"},"sameAs":["https:\/\/kaizen-blog.org"],"url":"https:\/\/kaizen-blog.org\/en\/author\/admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/batch_kaizennewsday-2026-03-21T082922.735.webp?fit=905%2C500&ssl=1","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":5954,"url":"https:\/\/kaizen-blog.org\/en\/strategiedebatte-oder-rechte-selbstvergewisserung-maximilian-krahs-allianz-mit-martin-sellner-wirft-grundsaetzliche-fragen-auf\/","url_meta":{"origin":32319,"position":0},"title":"Strategic Debate or Right-Wing Self-Affirmation? \u2013 Maximilian Krah\u2019s Alliance with Martin Sellner Raises Fundamental Questions","author":"Rainer Hofmann","date":"June 23, 2025","format":false,"excerpt":"Wenn Maximilian Krah \u00f6ffentlich auftritt, dann selten ohne Kalk\u00fcl. Der AfD-Politiker, seit Jahren umstritten wegen seiner N\u00e4he zu rechtsextremen Netzwerken und seiner Rolle in europ\u00e4ischen Skandalen, inszeniert sich gern als intellektuelles Gewissen einer neuen Rechten. In einem aktuellen Tweet k\u00fcndigt er eine strategische Debatte mit niemand Geringerem als Martin Sellner\u2026","rel":"","context":"In &quot;AFD - \"No Thanks\"&quot;","block_context":{"text":"AFD - \"No Thanks\"","link":"https:\/\/kaizen-blog.org\/en\/category\/afd-no-thanks\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/krah.webp?fit=850%2C508&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/krah.webp?fit=850%2C508&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/krah.webp?fit=850%2C508&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/krah.webp?fit=850%2C508&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":11092,"url":"https:\/\/kaizen-blog.org\/en\/wie-die-afd-ihre-eigenen-waehler-fuer-dumm-verkauft-maximilian-krah-luegen-am-laufenden-band\/","url_meta":{"origin":32319,"position":1},"title":"How the AfD Sells Its Own Voters for Stupid \u2013 Maximilian Krah, Lies on an Assembly Line","author":"Rainer Hofmann","date":"August 4, 2025","format":false,"excerpt":"Es gibt Propaganda, die macht nicht nur sprachlos \u2013 sie offenbart einen tiefen Zynismus gegen\u00fcber den eigenen W\u00e4hlern. Wer in diesen Tagen die \u00f6ffentlichen Aussagen von Maximilian Krah, einem der f\u00fchrenden K\u00f6pfe der AfD, verfolgt, erkennt eine Strategie, die auf dreiste Verdummung und gezielte Fehlinformation setzt. Krah und seine Gefolgsleute\u2026","rel":"","context":"In &quot;Dark Files&quot;","block_context":{"text":"Dark Files","link":"https:\/\/kaizen-blog.org\/en\/category\/investigativ\/dark-net\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/08\/batch_The-Kaizen-Blog-Online-Magazin81.webp?fit=900%2C508&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/08\/batch_The-Kaizen-Blog-Online-Magazin81.webp?fit=900%2C508&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/08\/batch_The-Kaizen-Blog-Online-Magazin81.webp?fit=900%2C508&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/08\/batch_The-Kaizen-Blog-Online-Magazin81.webp?fit=900%2C508&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4956,"url":"https:\/\/kaizen-blog.org\/en\/der-letzte-telegrammritter\/","url_meta":{"origin":32319,"position":2},"title":"The Last Telegram Knight","author":"Rainer Hofmann","date":"June 17, 2025","format":false,"excerpt":"Es war einmal ein Mann, der in einer Zeit lebte, die l\u00e4ngst vergangen war \u2013 nur wusste er es nicht. Dr. Maximilian Krah, seines Zeichens Bundestagsabgeordneter, X-Prediger und letzter Ritter der verlorenen Logik. Wenn er schreibt, dann schwitzt die Wahrheit. Nicht, weil sie ihm entgleitet, sondern weil sie sich vor\u2026","rel":"","context":"In &quot;AFD - \"No Thanks\"&quot;","block_context":{"text":"AFD - \"No Thanks\"","link":"https:\/\/kaizen-blog.org\/en\/category\/afd-no-thanks\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/krahkrah.webp?fit=850%2C508&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/krahkrah.webp?fit=850%2C508&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/krahkrah.webp?fit=850%2C508&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/krahkrah.webp?fit=850%2C508&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":10286,"url":"https:\/\/kaizen-blog.org\/en\/krahltastrophe-wie-maximilian-krah-das-abendland-rettet-indem-er-es-taeglich-untergehen-laesst\/","url_meta":{"origin":32319,"position":3},"title":"Krahltastrophe \u2013 How Maximilian Krah Saves the West by Letting It Collapse Every Day","author":"Rainer Hofmann","date":"July 27, 2025","format":false,"excerpt":"Es gibt Stimmen, die klingen wie ein s\u00e4chsischer Gongschlag ins kollektive Unwohlsein: laut, belehrend und stets bereit, sich selbst zu best\u00e4tigen. Dr. Maximilian Krah, der politische Instagramfilter f\u00fcr Untergangsstimmung, hat aus seinem X-Account ein Bollwerk der Daueremp\u00f6rung gebaut \u2013 eine Art ideologisches Tat\u00fctata mit Blaulicht und Meinungsfreiheits-Megafon. Zuerst das Drama\u2026","rel":"","context":"In &quot;AFD - \"No Thanks\"&quot;","block_context":{"text":"AFD - \"No Thanks\"","link":"https:\/\/kaizen-blog.org\/en\/category\/afd-no-thanks\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/07\/batch_Kopie-von-Kopie-von-Kopie-von-Kopie-von-Social-Kaizen64.webp?fit=900%2C508&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/07\/batch_Kopie-von-Kopie-von-Kopie-von-Kopie-von-Social-Kaizen64.webp?fit=900%2C508&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/07\/batch_Kopie-von-Kopie-von-Kopie-von-Kopie-von-Social-Kaizen64.webp?fit=900%2C508&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/07\/batch_Kopie-von-Kopie-von-Kopie-von-Kopie-von-Social-Kaizen64.webp?fit=900%2C508&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1317,"url":"https:\/\/kaizen-blog.org\/en\/eine-aerztliche-diagnose-von-dr-krah-a-medical-diagnosis-by-dr-krah\/","url_meta":{"origin":32319,"position":4},"title":"A Medical Diagnosis by Dr. Krah","author":"Rainer Hofmann","date":"May 19, 2025","format":false,"excerpt":"Die Autoimmunkrankheit Deutschland und das W\u00fcrzburger Experiment. Es war einmal ein Land im Herzen Europas, das an einer mysteri\u00f6sen Krankheit litt. Keine Sorge, es war keine k\u00f6rperliche Seuche, keine Pest, keine Pandemie \u2013 nein, es war etwas viel Schlimmeres: eine Autoimmunkrankheit des Geistes. Eine unsichtbare Seuche, die nach der pr\u00e4zisen\u2026","rel":"","context":"In &quot;Satire &amp; Hell&quot;","block_context":{"text":"Satire &amp; Hell","link":"https:\/\/kaizen-blog.org\/en\/category\/satire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/05\/Krah-AFD-Germany-scaled.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/05\/Krah-AFD-Germany-scaled.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/05\/Krah-AFD-Germany-scaled.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/05\/Krah-AFD-Germany-scaled.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/05\/Krah-AFD-Germany-scaled.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":16595,"url":"https:\/\/kaizen-blog.org\/en\/deutschland-ein-blick-in-den-moeglichen-abgrund\/","url_meta":{"origin":32319,"position":5},"title":"Germany \u2013 A Glimpse into the Possible Abyss","author":"Rainer Hofmann","date":"September 30, 2025","format":false,"excerpt":"Die Bundesrepublik taumelt. Nicht pl\u00f6tzlich, nicht \u00fcberraschend, sondern mit der schleichenden Gewissheit eines Zuges, der l\u00e4ngst die Weichen \u00fcberfahren hat. Was sich in den Social-Media-Feeds rechter Politiker abspielt, ist mehr als politisches Gepl\u00e4nkel \u2013 es ist das Drehbuch einer Transformation, die niemand bestellt hat und doch alle mittragen. Maximilian Krah,\u2026","rel":"","context":"In &quot;EU News&quot;","block_context":{"text":"EU News","link":"https:\/\/kaizen-blog.org\/en\/category\/eu-news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/09\/kaizen_22kaizenblognews103.webp?fit=905%2C505&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/09\/kaizen_22kaizenblognews103.webp?fit=905%2C505&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/09\/kaizen_22kaizenblognews103.webp?fit=905%2C505&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/09\/kaizen_22kaizenblognews103.webp?fit=905%2C505&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts\/32319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/comments?post=32319"}],"version-history":[{"count":0,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts\/32319\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/media\/32320"}],"wp:attachment":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/media?parent=32319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/categories?post=32319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/tags?post=32319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}