{"id":2913,"date":"2025-05-03T19:02:31","date_gmt":"2025-05-03T19:02:31","guid":{"rendered":"https:\/\/kaizen-blog.org\/?p=2913"},"modified":"2025-06-04T19:04:26","modified_gmt":"2025-06-04T19:04:26","slug":"wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln","status":"publish","type":"post","link":"https:\/\/kaizen-blog.org\/en\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/","title":{"rendered":"How a Far-Right Conspiracy Theorist Is Now Steering the U.S. National Security Council  -  You Can\u2019t Help but Shake Your Head"},"content":{"rendered":"<p>It begins with a personnel change but ends in a rupture of institutional foundations: Mike Waltz, President Donald Trump\u2019s national security adviser, is dismissed. No scandal. No public fallout. Just a statement - and a simultaneous nomination as U.S. Ambassador to the United Nations. A quiet demotion, as sterile as a calendar entry. What follows, however, is a story of concentrated power, ideological purging, and the troubling rise of a woman who, not long ago, was considered a fringe figure: Laura Loomer.<\/p>\n\n\n\n<p>n a functioning national security system, such a reshuffle might trigger analysis, debates over competence, strategy, and foreign policy coherence. But under Trump 2.0, the relevant question is no longer \u201cWho can guarantee security?\u201d - it\u2019s \u201cWhose voice does the president listen to?\u201d<\/p>\n\n\n\n<p>And he listens, not only to his newly favored diplomat, Marco Rubio, once ridiculed by Trump as \u201cLittle Marco\u201d and now serving simultaneously as Secretary of State and national security adviser, but also to Laura Loomer, a far-right activist who was banned by tech platforms, flagged by civil rights groups, and long viewed by much of the political establishment as dangerous. Today, she has become part of the machinery of decision-making.<\/p>\n\n\n\n<p>Loomer\u2019s influence is not rumor. It is documented.<\/p>\n\n\n\n<p>She herself claimed it was her personal suggestion to remove General Tim Haugh, the head of the NSA. Her reason: Haugh had ties to General Mark Milley, the former chairman of the Joint Chiefs who publicly opposed Trump\u2019s threats to deploy the military against protesters. Since then, Milley has been labeled an enemy. And in Trump\u2019s world, anyone connected to an enemy must go. The principle is simple. The implementation, authoritarian.<\/p>\n\n\n\n<p>A few weeks after Haugh\u2019s dismissal, Loomer spoke up again: she had advised Trump to fire Waltz as well. And again, the White House complied, without objection, without explanation. You could call it coincidence. Or you could see the pattern.<\/p>\n\n\n\n<p>A pattern that can be illustrated through five direct quotes, each one a blow to democratic values:<\/p>\n\n\n\n<p>1.<br>\u201cI\u2019m a proud Islamophobe. I believe Islam is a cancer. Period.\u201d\n(X\/Twitter, 2018)<br>(X\/Twitter, 2018)<\/p>\n\n\n\n<p>2.<br>\u201cThe Democrats are worse than Nazis. At least the Nazis were honest about their intentions.\u201d\n(YouTube, 2019)<br>(YouTube, 2019)<\/p>\n\n\n\n<p>3.<br>\u201cWe need internment camps for illegal immigrants and Muslims. Otherwise, they will take over our country.\u201d\n(Telegram, 2020 \u2013 archived by SPLC)<br>(Telegram, 2020 \u2013 archiviert von SPLC)<\/p>\n\n\n\n<p>4.<br>\u201cGeneral Milley is a Deep State traitor. Anyone working with him is a national security threat.\u201d\n(X\/Twitter, 2023)<br>(X\/Twitter, 2023)<\/p>\n\n\n\n<p>5.<br>\u201cI came to purge the GOP. Anyone who doesn\u2019t believe in Trump must go.\u201d\n(CPAC speech, 2024)<br>(CPAC-Rede, 2024)<\/p>\n\n\n\n<p>This kind of rhetoric - extremist, exclusionary, anti-democratic\u2014should disqualify someone from any role in policymaking. Instead, it now flows into decisions about war and peace. Loomer, who once handed out torn pages of the Quran in front of mosques to provoke outrage, is today shaping decisions about which generals the president trusts, and which he doesn\u2019t.<\/p>\n\n\n\n<p>Waltz wasn\u2019t radical enough. Not pliable enough.<\/p>\n\n\n\n<p>He had advocated for a tougher line on Russia, openly criticized Putin\u2019s expansionism, and supported U.S. policy in Ukraine. He belonged\u2014however cautiously, to the traditional national security establishment. That alone was enough to make him a liability in Trump\u2019s world.<\/p>\n\n\n\n<p>Rubio, by contrast - the man now holding two titles - is a symbol of adaptation. Once ridiculed, he has since bent the knee. He helped overhaul the State Department in Trump\u2019s image, gutted diversity initiatives, and tied diplomacy to ideological loyalty. Now he is also tasked with coordinating national security - during a time of overlapping global crises.<\/p>\n\n\n\n<p>The result is a National Security Council without coherence, without counterbalance, without structure.<\/p>\n\n\n\n<p>Where once there were professional briefings and structured channels, there are now Signal chats, Fox News appearances, and private meetings with influencers. Decision-making is impulsive, erratic, uncoordinated. Trump\u2019s \u201cAmerica First\u201d ideology has not only reshaped the content of U.S. foreign policy - it has hollowed out its infrastructure.<\/p>\n\n\n\n<p>And into that vacuum steps not expertise, but zealotry. Not deliberation, but noise. Not competence, but those like Loomer - loud enough to be heard, and dangerous enough to silence everything else.<\/p>\n\n\n\n<p>You can\u2019t help but shake your head.<\/p>\n\n\n\n<p>Not because it\u2019s shocking anymore, but because it\u2019s become numbingly predictable. We are witnessing the transformation of the U.S. national security apparatus into a stage for ideological purification. General after general is removed. Dissent is rebranded as disloyalty. And while the world looks to Washington for steady leadership - rational, diplomatic, anchored - Trump listens to a conspiracy theorist whispering names into his ear.<\/p>\n\n\n\n<p>This isn\u2019t an assault on institutions. It\u2019s their slow dismantling. From the inside. In plain sight.<\/p>\n\n\n\n<p>And as the doors keep spinning in Washington, each new appointment more surreal than the last, one can\u2019t help but wonder: Will Ernie from Sesame Street be named national security adviser next? In Trump\u2019s America, nothing is too absurd - so long as it\u2019s unhinged enough.<\/p>\n\n\n\n<p>What disqualifies Ernie?<br>He has character.<\/p>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"dark-america,history-x,trump-s-world\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1746298951\"\r\n\t            data-title=\"Wie eine ultrarechte Verschw\u00f6rungsagitatorin den US-Sicherheitsrat mitlenkt \u2013 Man kann nur noch den Kopf sch\u00fctteln\" \r\n\t            data-home=\"https:\/\/kaizen-blog.org\/en\/\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Es beginnt mit einer Personalie, endet aber in einer Ersch\u00fctterung institutioneller Grundfesten: Mike Waltz, der nationale Sicherheitsberater von Pr\u00e4sident Donald Trump, wird entlassen. Kein Skandal. Keine \u00f6ffentliche Abrechnung. Nur eine Mitteilung \u2013 und eine gleichzeitige Nominierung zum UN-Botschafter. Eine stille Degradierung, so sachlich wie ein Eintrag in einem Kalender. Was aber folgt, ist eine Geschichte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2914,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[46,40,41],"tags":[],"class_list":["post-2913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dark-america","category-history-x","category-trump-s-world"],"featured_image_src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/loomer-trump.webp?fit=988%2C504&ssl=1","author_info":{"display_name":"Rainer Hofmann","author_link":"https:\/\/kaizen-blog.org\/en\/author\/admin\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wie eine ultrarechte Verschw\u00f6rungsagitatorin den US-Sicherheitsrat mitlenkt \u2013 Man kann nur noch den Kopf sch\u00fctteln - The Kaizen Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kaizen-blog.org\/en\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie eine ultrarechte Verschw\u00f6rungsagitatorin den US-Sicherheitsrat mitlenkt \u2013 Man kann nur noch den Kopf sch\u00fctteln\" \/>\n<meta property=\"og:description\" content=\"Es beginnt mit einer Personalie, endet aber in einer Ersch\u00fctterung institutioneller Grundfesten: Mike Waltz, der nationale Sicherheitsberater von Pr\u00e4sident Donald Trump, wird entlassen. Kein Skandal. Keine \u00f6ffentliche Abrechnung. Nur eine Mitteilung \u2013 und eine gleichzeitige Nominierung zum UN-Botschafter. Eine stille Degradierung, so sachlich wie ein Eintrag in einem Kalender. Was aber folgt, ist eine Geschichte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kaizen-blog.org\/en\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/\" \/>\n<meta property=\"og:site_name\" content=\"The Kaizen Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rainer.hofmann.2025\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-03T19:02:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-04T19:04:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/loomer-trump.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"988\" \/>\n\t<meta property=\"og:image:height\" content=\"504\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Rainer Hofmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rainer Hofmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\\\/\"},\"author\":{\"name\":\"Rainer Hofmann\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\"},\"headline\":\"Wie eine ultrarechte Verschw\u00f6rungsagitatorin den US-Sicherheitsrat mitlenkt \u2013 Man kann nur noch den Kopf sch\u00fctteln\",\"datePublished\":\"2025-05-03T19:02:31+00:00\",\"dateModified\":\"2025-06-04T19:04:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\\\/\"},\"wordCount\":841,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/loomer-trump.webp?fit=988%2C504&ssl=1\",\"articleSection\":[\"Dark America\",\"History X\",\"Trumpland\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/kaizen-blog.org\\\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\\\/\",\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\\\/\",\"name\":\"Wie eine ultrarechte Verschw\u00f6rungsagitatorin den US-Sicherheitsrat mitlenkt \u2013 Man kann nur noch den Kopf sch\u00fctteln - The Kaizen Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/loomer-trump.webp?fit=988%2C504&ssl=1\",\"datePublished\":\"2025-05-03T19:02:31+00:00\",\"dateModified\":\"2025-06-04T19:04:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kaizen-blog.org\\\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/loomer-trump.webp?fit=988%2C504&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/loomer-trump.webp?fit=988%2C504&ssl=1\",\"width\":988,\"height\":504},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/kaizen-blog.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wie eine ultrarechte Verschw\u00f6rungsagitatorin den US-Sicherheitsrat mitlenkt \u2013 Man kann nur noch den Kopf sch\u00fctteln\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#website\",\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/\",\"name\":\"The Kaizen Blog\",\"description\":\"Investigativer Journalismus\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kaizen-blog.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\",\"name\":\"Rainer Hofmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"caption\":\"Rainer Hofmann\"},\"sameAs\":[\"https:\\\/\\\/kaizen-blog.org\"],\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie eine ultrarechte Verschw\u00f6rungsagitatorin den US-Sicherheitsrat mitlenkt \u2013 Man kann nur noch den Kopf sch\u00fctteln - The Kaizen Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kaizen-blog.org\/en\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/","og_locale":"en_US","og_type":"article","og_title":"Wie eine ultrarechte Verschw\u00f6rungsagitatorin den US-Sicherheitsrat mitlenkt \u2013 Man kann nur noch den Kopf sch\u00fctteln","og_description":"Es beginnt mit einer Personalie, endet aber in einer Ersch\u00fctterung institutioneller Grundfesten: Mike Waltz, der nationale Sicherheitsberater von Pr\u00e4sident Donald Trump, wird entlassen. Kein Skandal. Keine \u00f6ffentliche Abrechnung. Nur eine Mitteilung \u2013 und eine gleichzeitige Nominierung zum UN-Botschafter. Eine stille Degradierung, so sachlich wie ein Eintrag in einem Kalender. Was aber folgt, ist eine Geschichte [&hellip;]","og_url":"https:\/\/kaizen-blog.org\/en\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/","og_site_name":"The Kaizen Blog","article_publisher":"https:\/\/www.facebook.com\/rainer.hofmann.2025\/","article_published_time":"2025-05-03T19:02:31+00:00","article_modified_time":"2025-06-04T19:04:26+00:00","og_image":[{"width":988,"height":504,"url":"https:\/\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/loomer-trump.webp","type":"image\/webp"}],"author":"Rainer Hofmann","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rainer Hofmann","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kaizen-blog.org\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/#article","isPartOf":{"@id":"https:\/\/kaizen-blog.org\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/"},"author":{"name":"Rainer Hofmann","@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0"},"headline":"Wie eine ultrarechte Verschw\u00f6rungsagitatorin den US-Sicherheitsrat mitlenkt \u2013 Man kann nur noch den Kopf sch\u00fctteln","datePublished":"2025-05-03T19:02:31+00:00","dateModified":"2025-06-04T19:04:26+00:00","mainEntityOfPage":{"@id":"https:\/\/kaizen-blog.org\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/"},"wordCount":841,"commentCount":0,"image":{"@id":"https:\/\/kaizen-blog.org\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/loomer-trump.webp?fit=988%2C504&ssl=1","articleSection":["Dark America","History X","Trumpland"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kaizen-blog.org\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kaizen-blog.org\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/","url":"https:\/\/kaizen-blog.org\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/","name":"Wie eine ultrarechte Verschw\u00f6rungsagitatorin den US-Sicherheitsrat mitlenkt \u2013 Man kann nur noch den Kopf sch\u00fctteln - The Kaizen Blog","isPartOf":{"@id":"https:\/\/kaizen-blog.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kaizen-blog.org\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/#primaryimage"},"image":{"@id":"https:\/\/kaizen-blog.org\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/loomer-trump.webp?fit=988%2C504&ssl=1","datePublished":"2025-05-03T19:02:31+00:00","dateModified":"2025-06-04T19:04:26+00:00","author":{"@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0"},"breadcrumb":{"@id":"https:\/\/kaizen-blog.org\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kaizen-blog.org\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kaizen-blog.org\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/#primaryimage","url":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/loomer-trump.webp?fit=988%2C504&ssl=1","contentUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/loomer-trump.webp?fit=988%2C504&ssl=1","width":988,"height":504},{"@type":"BreadcrumbList","@id":"https:\/\/kaizen-blog.org\/wie-eine-ultrarechte-verschwoerungsagitatorin-den-us-sicherheitsrat-mitlenkt-man-kann-nur-noch-den-kopf-schuetteln\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kaizen-blog.org\/"},{"@type":"ListItem","position":2,"name":"Wie eine ultrarechte Verschw\u00f6rungsagitatorin den US-Sicherheitsrat mitlenkt \u2013 Man kann nur noch den Kopf sch\u00fctteln"}]},{"@type":"WebSite","@id":"https:\/\/kaizen-blog.org\/#website","url":"https:\/\/kaizen-blog.org\/","name":"The Kaizen Blog","description":"Investigative Journalism","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kaizen-blog.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0","name":"Rainer Hofmann","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","url":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","contentUrl":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","caption":"Rainer Hofmann"},"sameAs":["https:\/\/kaizen-blog.org"],"url":"https:\/\/kaizen-blog.org\/en\/author\/admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/loomer-trump.webp?fit=988%2C504&ssl=1","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":27918,"url":"https:\/\/kaizen-blog.org\/en\/unsere-recherche-der-staat-gegen-die-gesellschaft-wie-die-usa-soziale-konflikte-als-terrorismus-definieren-und-europa-folgen-koennte\/","url_meta":{"origin":2913,"position":0},"title":"Our Investigation: The State Against Society \u2013 How the US Redefines Social Conflict as Terrorism and Europe Could Follow","author":"Rainer Hofmann","date":"February 2, 2026","format":false,"excerpt":"Die Fixierung auf Gr\u00f6nland, auf Arktisrouten, seltene Erden und geopolitische Drohkulissen geh\u00f6rt zu den \u00f6ffentlichen Ritualen dieser Regierung. Doch w\u00e4hrend Donald Trump mit milit\u00e4rischen Fantasien nach Norden blickt, richtet das US-Heimatschutzministerium seinen tats\u00e4chlichen Fokus nach innen. Nicht auf \u00e4u\u00dfere Gegner, nicht auf Staaten oder Organisationen jenseits der Grenzen, sondern auf\u2026","rel":"","context":"In &quot;Documentation&quot;","block_context":{"text":"Documentation","link":"https:\/\/kaizen-blog.org\/en\/category\/documentation\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/02\/batch_kaizennewsday-2026-02-02T054843.818.webp?fit=905%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/02\/batch_kaizennewsday-2026-02-02T054843.818.webp?fit=905%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/02\/batch_kaizennewsday-2026-02-02T054843.818.webp?fit=905%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/02\/batch_kaizennewsday-2026-02-02T054843.818.webp?fit=905%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":24086,"url":"https:\/\/kaizen-blog.org\/en\/venezuela-ruft-den-sicherheitsrat-caracas-spricht-von-kolonialer-anmassung-der-usa\/","url_meta":{"origin":2913,"position":1},"title":"Venezuela Calls the Security Council \u2013 Caracas Speaks of U.S. Colonial Arrogance","author":"Rainer Hofmann","date":"December 18, 2025","format":false,"excerpt":"Der UN-Sicherheitsrat tritt auf Antrag Venezuelas zu einer Dringlichkeitssitzung zusammen. Das Treffen ist f\u00fcr Dienstag um 15 Uhr Ostk\u00fcstenzeit angesetzt, wie Slowenien mitteilte, das im laufenden Monat den Vorsitz im Sicherheitsrat innehat. Ausl\u00f6ser ist eine formelle Beschwerde der venezolanischen Regierung \u00fcber das, was sie als fortgesetzte aggressive Handlungen der Vereinigten\u2026","rel":"","context":"In &quot;Human Rights&quot;","block_context":{"text":"Human Rights","link":"https:\/\/kaizen-blog.org\/en\/category\/investigativ\/human-rights\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/12\/kaizenvenlogo.webp?fit=900%2C508&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/12\/kaizenvenlogo.webp?fit=900%2C508&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/12\/kaizenvenlogo.webp?fit=900%2C508&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/12\/kaizenvenlogo.webp?fit=900%2C508&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":28136,"url":"https:\/\/kaizen-blog.org\/en\/05-februar-2026-kurznachrichten\/","url_meta":{"origin":2913,"position":2},"title":"February 5, 2026 \u2013 Short News","author":"TEAM KAIZEN BLOG","date":"February 5, 2026","format":false,"excerpt":"Polizeianw\u00e4rter festgenommen \u2013 Streit zwischen Stadt und Bundesbeh\u00f6rden eskaliert! Die Festnahme eines Polizeianw\u00e4rters in New Orleans hat einen offenen Konflikt zwischen Stadtverwaltung und Bundesbeh\u00f6rden ausgel\u00f6st. Der 46-j\u00e4hrige Kameruner Larry Temah befand sich mitten in der Ausbildung an der Polizeiakademie, als Beamte der Einwanderungsbeh\u00f6rde ihn festnahmen. Die Beh\u00f6rden verweisen auf eine\u2026","rel":"","context":"In &quot;+++ Kaizen News Ticker +++&quot;","block_context":{"text":"+++ Kaizen News Ticker +++","link":"https:\/\/kaizen-blog.org\/en\/category\/ticker\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/02\/kaizenlive-2026-02-05T013123.463.webp?fit=905%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/02\/kaizenlive-2026-02-05T013123.463.webp?fit=905%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/02\/kaizenlive-2026-02-05T013123.463.webp?fit=905%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/02\/kaizenlive-2026-02-05T013123.463.webp?fit=905%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3994,"url":"https:\/\/kaizen-blog.org\/en\/was-hatten-die-bloss-in-den-keksen-wenn-die-spd-russland-ploetzlich-umarmen-will\/","url_meta":{"origin":2913,"position":3},"title":"What on Earth Was in Those Cookies? \u2013 When the SPD Suddenly Wants to Hug Russia","author":"Rainer Hofmann","date":"June 11, 2025","format":false,"excerpt":"Es beginnt wie eine Szene aus einem schlecht gespielten Polit-Theaterst\u00fcck. Vier \u00e4ltere Herren, allesamt mit Parteibuch, Feder und friedensbewegtem Pathos, schreiben ein Manifest. Nicht irgendeines \u2013 sondern ein Dokument, das Deutschland sicherheitspolitisch zur\u00fcck in die 1980er katapultieren will. Rolf M\u00fctzenich, Ralf Stegner, Norbert Walter-Borjans und Hans Eichel, flankiert von \u00fcber\u2026","rel":"","context":"In &quot;Inferno Ukraine&quot;","block_context":{"text":"Inferno Ukraine","link":"https:\/\/kaizen-blog.org\/en\/category\/inferno-ukraine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/spd-russia.webp?fit=850%2C508&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/spd-russia.webp?fit=850%2C508&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/spd-russia.webp?fit=850%2C508&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/spd-russia.webp?fit=850%2C508&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":27952,"url":"https:\/\/kaizen-blog.org\/en\/recherchen-zeigen-auf-wie-arabische-monarchien-trump-und-die-europaeische-rechte-ein-system-stabilisieren-das-kriege-instabilitaet-und-flucht-erzeugt\/","url_meta":{"origin":2913,"position":4},"title":"Our Investigation Reveals \u2013 How Arab Monarchies, Trump, and the European Right Stabilize a System That Produces Wars, Instability, and Flight","author":"Rainer Hofmann","date":"February 2, 2026","format":false,"excerpt":"Ende Dezember schlugen saudi-arabische Kampfflugzeuge im jemenitischen Hafen Mukalla zu. Getroffen wurde nach Darstellung Riads ein aus den Emiraten gelieferter Waffentransport, bestimmt f\u00fcr den S\u00fcdlichen \u00dcbergangsrat. Damit wurde aus einer lange schwelenden Rivalit\u00e4t zwischen Saudi-Arabien und den Vereinigten Arabischen Emiraten ein offener milit\u00e4rischer Konflikt. Eine neue gro\u00dfe Konfrontation am Golf\u2026","rel":"","context":"In &quot;Topstory&quot;","block_context":{"text":"Topstory","link":"https:\/\/kaizen-blog.org\/en\/category\/topstory\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/02\/kaizennewsday-2026-02-02T164018.868.webp?fit=905%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/02\/kaizennewsday-2026-02-02T164018.868.webp?fit=905%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/02\/kaizennewsday-2026-02-02T164018.868.webp?fit=905%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/02\/kaizennewsday-2026-02-02T164018.868.webp?fit=905%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":5176,"url":"https:\/\/kaizen-blog.org\/en\/trump-gegen-gabbard-wie-der-praesident-seine-geheimdienstchefin-demontiert\/","url_meta":{"origin":2913,"position":5},"title":"Trump vs. Gabbard \u2013 How the President Is Dismantling His Intelligence Chief","author":"Rainer Hofmann","date":"June 18, 2025","format":false,"excerpt":"Im Schatten wachsender Spannungen zwischen den USA, Iran und Israel bahnt sich ein interner Machtkampf an, der die F\u00fchrungsstruktur der nationalen Sicherheitsbeh\u00f6rden ersch\u00fcttern k\u00f6nnte: Pr\u00e4sident Donald Trump, so berichten Insider aus dem Wei\u00dfen Haus, verliert zunehmend das Vertrauen in seine Direktorin der Nationalen Nachrichtendienste, Tulsi Gabbard \u2013 und erw\u00e4gt sogar\u2026","rel":"","context":"In &quot;Daylight&quot;","block_context":{"text":"Daylight","link":"https:\/\/kaizen-blog.org\/en\/category\/daylight\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/gabbard-bye.webp?fit=850%2C508&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/gabbard-bye.webp?fit=850%2C508&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/gabbard-bye.webp?fit=850%2C508&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/06\/gabbard-bye.webp?fit=850%2C508&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts\/2913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/comments?post=2913"}],"version-history":[{"count":0,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts\/2913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/media\/2914"}],"wp:attachment":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/media?parent=2913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/categories?post=2913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/tags?post=2913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}