{"id":15478,"date":"2025-09-17T19:42:10","date_gmt":"2025-09-17T17:42:10","guid":{"rendered":"https:\/\/kaizen-blog.org\/?p=15478"},"modified":"2025-09-17T19:42:13","modified_gmt":"2025-09-17T17:42:13","slug":"ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses","status":"publish","type":"post","link":"https:\/\/kaizen-blog.org\/en\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/","title":{"rendered":"A Country at an Inflection Point - Obama Warns of the Deadly Normalization of Political Hate"},"content":{"rendered":"<p>Barack Obama chose the words that a President Donald Trump has lacked for years: clear, unequivocal, without excuses. After the murder of Charlie Kirk, the former US president spoke in Erie, Pennsylvania, of an \u201cinflection point\u201d for the United States - a moment when it will be decided whether the country will continue on the path of democracy or finally slip into the abyss of violence. \u201cThere are no ifs, ands or buts: The basic principle of our system is that we can argue, debate, yes even clash fiercely, without resorting to violence,\u201d Obama said. \u201cAnd when violence is normalized, even if it affects the supposedly \u2018other\u2019 side, then that is a threat to all of us.\u201d<\/p>\n\n\n\n<p>It was an appearance that in its clarity recalled those rare moments when presidents, across party and ideological lines, invoked what is common. Obama himself referred to the eulogy in Charleston after the racist massacre of 2015, as well as to George W. Bush\u2019s conduct after September 11. He made clear what Trump has refused in every one of his reactions: \u201cThe task of a president in crisis is to constantly remind us of the bonds that unite us.\u201d<\/p>\n\n\n\n<p>But since Kirk\u2019s murder, Trump has done the opposite. Instead of moderation he opts for escalation, calling political opponents \u201cvermin\u201d and \u201cenemies,\u201d driving his followers with threats against the \u201cradical left,\u201d and trying to instrumentalize the outrage over the act for his own purposes. It is a dangerous pattern that Obama named with full clarity: a president who not only breaks the norms of his predecessors but with every step pushes aside the guardrails of democracy. \u201cWhat you are seeing is the notion that many of the norms and rules that I felt bound by as president, that George Bush felt bound by as president, suddenly no longer apply,\u201d Obama warned. \u201cAnd that is exactly what makes this moment so dangerous.\u201d<\/p>\n\n\n\n<p>His words come in a situation overflowing with symbols. While in Orem, Utah, hundreds lay flowers at an improvised memorial for Charlie Kirk, while Kirk\u2019s supporters in social networks speak of a martyr, the alleged murderer Tyler Robinson sits in pretrial detention. In the interrogation protocols he confesses by text message to his partner to have fired the shot. A young man, 22 years old, caught in a vortex of personal trauma and political hate - and now become the starting point of a debate that tears the country apart.<\/p>\n\n\n\n<p>Obama reacted as statesmen should: he spoke the obvious, without regard for partisan noise. He publicly prayed with his wife Michelle for Kirk\u2019s family, he said that he rejected many of Kirk\u2019s positions, but that this rejection must never relativize the murder. \u201cIt was a tragedy, and I mourn with his family,\u201d he emphasized. Words that should seem self-evident - and that in America in 2025 sound almost revolutionary. That Trump\u2019s White House immediately shot back and insulted Obama as the \u201carchitect of modern division\u201d was only the next turn in a cycle of hostility. Spokeswoman Abigail Jackson claimed that Obama had dug trenches during his term instead of closing them. Yet it is exactly this reversal of cause and effect that makes Obama\u2019s warnings so explosive: whoever trivializes violence, whoever feeds it with new enemy images, destroys the foundation of democracy.<\/p>\n\n\n\n<p>Obama also highlighted in his speech what today almost gets lost: that despite everything there are still voices of reason. He praised the Republican governor of Utah, Spencer Cox, who after Kirk\u2019s death had called for moderation and decency. \u201cWe disagree on a whole bunch of stuff,\u201d Obama said, \u201cbut his words show that it is possible to argue and yet uphold a basic code of public interaction.\u201d This admonition to civility, to a return to the simplest forms of decency, is what makes the moment so heavy and at the same time so hopeful. The country is at a point that Obama calls an \u201cinflection point\u201d - a fork in the road at which words can finally turn into deeds. The murder of Charlie Kirk has made tangible the danger that has long been hidden in the hate slogans, in the martial threats, and in the political instrumentalization of hate. Now it is up to Americans whether they accept the course of violence - or whether they, as Obama demands, once again remember the bonds that unite them despite all differences.<\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<!-- Kaizen Blog \u2013 Support-Kasten (responsive, mobil\/tablet\/desktop) -->\n<div class=\"kb-support-card\" role=\"complementary\" aria-label=\"Unterst\u00fctzen Sie den Kaizen Blog\">\n  <style>\n    .kb-support-card{\n      --kb-accent-1:#39ff14; \/* Neon-Gr\u00fcn *\/\n      --kb-accent-2:#00cc44;\n      --kb-text:#0a0a0a;\n      --kb-bg:#ffffff;\n      --kb-border:rgba(0,0,0,.08);\n\n      max-width: 720px;\n      margin: 16px auto;\n      padding: 18px 20px;\n      background: var(--kb-bg);\n      color: var(--kb-text);\n      border: 1px solid var(--kb-border);\n      border-radius: 16px;\n      box-shadow: 0 8px 24px rgba(0,0,0,.06);\n      font-family: -apple-system,BlinkMacSystemFont,\"Segoe UI\",Roboto,\"Helvetica Neue\",Arial,system-ui,\"Apple Color Emoji\",\"Segoe UI Emoji\";\n      line-height: 1.55;\n    }\n    .kb-support-card p{margin:0 0 .8rem 0; font-size: 1rem;}\n    .kb-support-card .kb-lead{font-weight: 700; font-size: 1.05rem;}\n    .kb-support-actions{margin-top:.25rem; display:flex; gap:.75rem; align-items:center; flex-wrap:wrap}\n\n    .kb-support-btn{\n      display:inline-block;\n      padding: 9px 18px; \/* 20% kleiner *\/\n      border-radius: 9999px;\n      background: linear-gradient(90deg,var(--kb-accent-1),var(--kb-accent-2));\n      color:#000;\n      text-decoration:none;\n      font-weight:700;\n      letter-spacing:.2px;\n      font-size: 0.9rem;\n      box-shadow: 0 10px 22px rgba(0,255,0,.4);\n      transition: transform .06s ease, box-shadow .2s ease, filter .2s ease;\n      white-space: nowrap;\n    }\n    .kb-support-btn:hover{\n      transform: translateY(-1px);\n      box-shadow: 0 12px 28px rgba(0,255,0,.55);\n      filter: brightness(1.08);\n    }\n    .kb-support-btn:active{transform: translateY(0);}\n    .kb-support-btn:focus-visible{\n      outline:3px solid rgba(0,255,0,.5);\n      outline-offset:2px;\n      border-radius:9999px\n    }\n\n    @media (min-width:640px){\n      .kb-support-card{padding:22px 24px}\n      .kb-support-btn{padding:11px 22px; font-size:0.95rem}\n    }\n  <\/style>\n\n  <p class=\"kb-lead\">Investigative journalism requires courage, conviction \u2013 and your support.<\/p>\n  <p>Please support our journalistic fight against right-wing populism and human rights violations. We do not want to finance our work through a paywall, so that everyone can read our investigations \u2013 regardless of income or background.<\/p>\n\n  <div class=\"kb-support-actions\">\n    <a class=\"kb-support-btn\"\n       href=\"https:\/\/kaizen-blog.org\/en\/unterstuetzen-sie-unser-arbeit\/\"\n       rel=\"noopener\"\n       aria-label=\"Support Kaizen \u2013 \u00f6ffnet auf dieser Seite\">\n      Support Kaizen\n    <\/a>\n  <\/div>\n<\/div>\n\n\n\n\n<div style=\"height:82px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"topstory,trump-s-world,trump-usa\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1758138130\"\r\n\t            data-title=\"Ein Land am Wendepunkt \u2013 Obama warnt vor der t\u00f6dlichen Normalisierung des politischen Hasses\" \r\n\t            data-home=\"https:\/\/kaizen-blog.org\/en\/\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Barack Obama hat die Worte gew\u00e4hlt, die einem Pr\u00e4sidenten Donald Trump seit Jahren fehlen: Klar, unmissverst\u00e4ndlich, ohne Ausfl\u00fcchte. Nach dem Mord an Charlie Kirk sprach der fr\u00fchere US-Pr\u00e4sident in Erie, Pennsylvania, von einem \u201eWendepunkt\u201c f\u00fcr die Vereinigten Staaten \u2013 einem Moment, in dem sich entscheiden wird, ob das Land den Pfad der Demokratie weitergeht oder [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,41,1],"tags":[],"class_list":["post-15478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-topstory","category-trump-s-world","category-trump-usa"],"featured_image_src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/09\/Kaizen-Blog7.webp?fit=905%2C500&ssl=1","author_info":{"display_name":"Rainer Hofmann","author_link":"https:\/\/kaizen-blog.org\/en\/author\/admin\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ein Land am Wendepunkt \u2013 Obama warnt vor der t\u00f6dlichen Normalisierung des politischen Hasses - The Kaizen Blog<\/title>\n<meta name=\"description\" content=\"Barack Obama hat die Worte gew\u00e4hlt, die einem Pr\u00e4sidenten Donald Trump seit Jahren fehlen: Klar, unmissverst\u00e4ndlich, ohne Ausfl\u00fcchte. Nach dem Mord an Charlie Kirk sprach der fr\u00fchere US-Pr\u00e4sident in Erie, Pennsylvania, von einem \u201eWendepunkt\u201c f\u00fcr die Vereinigten Staaten \u2013 einem Moment, in dem sich entscheiden wird, ob das Land den Pfad der Demokratie weitergeht oder endg\u00fcltig in den Abgrund der Gewalt rutscht. \u201eEs gibt keine Wenns und Abers: Das Grundprinzip unseres Systems ist, dass wir uns streiten, debattieren, ja auch heftig auseinandersetzen k\u00f6nnen,...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kaizen-blog.org\/en\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein Land am Wendepunkt \u2013 Obama warnt vor der t\u00f6dlichen Normalisierung des politischen Hasses\" \/>\n<meta property=\"og:description\" content=\"Barack Obama hat die Worte gew\u00e4hlt, die einem Pr\u00e4sidenten Donald Trump seit Jahren fehlen: Klar, unmissverst\u00e4ndlich, ohne Ausfl\u00fcchte. Nach dem Mord an Charlie Kirk sprach der fr\u00fchere US-Pr\u00e4sident in Erie, Pennsylvania, von einem \u201eWendepunkt\u201c f\u00fcr die Vereinigten Staaten \u2013 einem Moment, in dem sich entscheiden wird, ob das Land den Pfad der Demokratie weitergeht oder endg\u00fcltig in den Abgrund der Gewalt rutscht. \u201eEs gibt keine Wenns und Abers: Das Grundprinzip unseres Systems ist, dass wir uns streiten, debattieren, ja auch heftig auseinandersetzen k\u00f6nnen,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kaizen-blog.org\/en\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/\" \/>\n<meta property=\"og:site_name\" content=\"The Kaizen Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rainer.hofmann.2025\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-17T17:42:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-17T17:42:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kaizen-blog.org\/wp-content\/uploads\/2025\/09\/Kaizen-Blog7.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"905\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Rainer Hofmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rainer Hofmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\\\/\"},\"author\":{\"name\":\"Rainer Hofmann\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\"},\"headline\":\"Ein Land am Wendepunkt \u2013 Obama warnt vor der t\u00f6dlichen Normalisierung des politischen Hasses\",\"datePublished\":\"2025-09-17T17:42:10+00:00\",\"dateModified\":\"2025-09-17T17:42:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\\\/\"},\"wordCount\":809,\"commentCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Kaizen-Blog7.webp?fit=905%2C500&ssl=1\",\"articleSection\":[\"Topstory\",\"Trumpland\",\"USA\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/kaizen-blog.org\\\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\\\/\",\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\\\/\",\"name\":\"Ein Land am Wendepunkt \u2013 Obama warnt vor der t\u00f6dlichen Normalisierung des politischen Hasses - The Kaizen Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Kaizen-Blog7.webp?fit=905%2C500&ssl=1\",\"datePublished\":\"2025-09-17T17:42:10+00:00\",\"dateModified\":\"2025-09-17T17:42:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\"},\"description\":\"Barack Obama hat die Worte gew\u00e4hlt, die einem Pr\u00e4sidenten Donald Trump seit Jahren fehlen: Klar, unmissverst\u00e4ndlich, ohne Ausfl\u00fcchte. Nach dem Mord an Charlie Kirk sprach der fr\u00fchere US-Pr\u00e4sident in Erie, Pennsylvania, von einem \u201eWendepunkt\u201c f\u00fcr die Vereinigten Staaten \u2013 einem Moment, in dem sich entscheiden wird, ob das Land den Pfad der Demokratie weitergeht oder endg\u00fcltig in den Abgrund der Gewalt rutscht. \u201eEs gibt keine Wenns und Abers: Das Grundprinzip unseres Systems ist, dass wir uns streiten, debattieren, ja auch heftig auseinandersetzen k\u00f6nnen,...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kaizen-blog.org\\\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Kaizen-Blog7.webp?fit=905%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/kaizen-blog.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Kaizen-Blog7.webp?fit=905%2C500&ssl=1\",\"width\":905,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/kaizen-blog.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein Land am Wendepunkt \u2013 Obama warnt vor der t\u00f6dlichen Normalisierung des politischen Hasses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#website\",\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/\",\"name\":\"The Kaizen Blog\",\"description\":\"Investigativer Journalismus\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kaizen-blog.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kaizen-blog.org\\\/#\\\/schema\\\/person\\\/7d3fc7346e2501a389ea3daa48b99ad0\",\"name\":\"Rainer Hofmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials\",\"caption\":\"Rainer Hofmann\"},\"sameAs\":[\"https:\\\/\\\/kaizen-blog.org\"],\"url\":\"https:\\\/\\\/kaizen-blog.org\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein Land am Wendepunkt \u2013 Obama warnt vor der t\u00f6dlichen Normalisierung des politischen Hasses - The Kaizen Blog","description":"Barack Obama hat die Worte gew\u00e4hlt, die einem Pr\u00e4sidenten Donald Trump seit Jahren fehlen: Klar, unmissverst\u00e4ndlich, ohne Ausfl\u00fcchte. Nach dem Mord an Charlie Kirk sprach der fr\u00fchere US-Pr\u00e4sident in Erie, Pennsylvania, von einem \u201eWendepunkt\u201c f\u00fcr die Vereinigten Staaten \u2013 einem Moment, in dem sich entscheiden wird, ob das Land den Pfad der Demokratie weitergeht oder endg\u00fcltig in den Abgrund der Gewalt rutscht. \u201eEs gibt keine Wenns und Abers: Das Grundprinzip unseres Systems ist, dass wir uns streiten, debattieren, ja auch heftig auseinandersetzen k\u00f6nnen,...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kaizen-blog.org\/en\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/","og_locale":"en_US","og_type":"article","og_title":"Ein Land am Wendepunkt \u2013 Obama warnt vor der t\u00f6dlichen Normalisierung des politischen Hasses","og_description":"Barack Obama hat die Worte gew\u00e4hlt, die einem Pr\u00e4sidenten Donald Trump seit Jahren fehlen: Klar, unmissverst\u00e4ndlich, ohne Ausfl\u00fcchte. Nach dem Mord an Charlie Kirk sprach der fr\u00fchere US-Pr\u00e4sident in Erie, Pennsylvania, von einem \u201eWendepunkt\u201c f\u00fcr die Vereinigten Staaten \u2013 einem Moment, in dem sich entscheiden wird, ob das Land den Pfad der Demokratie weitergeht oder endg\u00fcltig in den Abgrund der Gewalt rutscht. \u201eEs gibt keine Wenns und Abers: Das Grundprinzip unseres Systems ist, dass wir uns streiten, debattieren, ja auch heftig auseinandersetzen k\u00f6nnen,...","og_url":"https:\/\/kaizen-blog.org\/en\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/","og_site_name":"The Kaizen Blog","article_publisher":"https:\/\/www.facebook.com\/rainer.hofmann.2025\/","article_published_time":"2025-09-17T17:42:10+00:00","article_modified_time":"2025-09-17T17:42:13+00:00","og_image":[{"width":905,"height":500,"url":"https:\/\/kaizen-blog.org\/wp-content\/uploads\/2025\/09\/Kaizen-Blog7.webp","type":"image\/webp"}],"author":"Rainer Hofmann","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rainer Hofmann","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kaizen-blog.org\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/#article","isPartOf":{"@id":"https:\/\/kaizen-blog.org\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/"},"author":{"name":"Rainer Hofmann","@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0"},"headline":"Ein Land am Wendepunkt \u2013 Obama warnt vor der t\u00f6dlichen Normalisierung des politischen Hasses","datePublished":"2025-09-17T17:42:10+00:00","dateModified":"2025-09-17T17:42:13+00:00","mainEntityOfPage":{"@id":"https:\/\/kaizen-blog.org\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/"},"wordCount":809,"commentCount":5,"image":{"@id":"https:\/\/kaizen-blog.org\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/09\/Kaizen-Blog7.webp?fit=905%2C500&ssl=1","articleSection":["Topstory","Trumpland","USA"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kaizen-blog.org\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kaizen-blog.org\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/","url":"https:\/\/kaizen-blog.org\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/","name":"Ein Land am Wendepunkt \u2013 Obama warnt vor der t\u00f6dlichen Normalisierung des politischen Hasses - The Kaizen Blog","isPartOf":{"@id":"https:\/\/kaizen-blog.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kaizen-blog.org\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/#primaryimage"},"image":{"@id":"https:\/\/kaizen-blog.org\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/09\/Kaizen-Blog7.webp?fit=905%2C500&ssl=1","datePublished":"2025-09-17T17:42:10+00:00","dateModified":"2025-09-17T17:42:13+00:00","author":{"@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0"},"description":"Barack Obama hat die Worte gew\u00e4hlt, die einem Pr\u00e4sidenten Donald Trump seit Jahren fehlen: Klar, unmissverst\u00e4ndlich, ohne Ausfl\u00fcchte. Nach dem Mord an Charlie Kirk sprach der fr\u00fchere US-Pr\u00e4sident in Erie, Pennsylvania, von einem \u201eWendepunkt\u201c f\u00fcr die Vereinigten Staaten \u2013 einem Moment, in dem sich entscheiden wird, ob das Land den Pfad der Demokratie weitergeht oder endg\u00fcltig in den Abgrund der Gewalt rutscht. \u201eEs gibt keine Wenns und Abers: Das Grundprinzip unseres Systems ist, dass wir uns streiten, debattieren, ja auch heftig auseinandersetzen k\u00f6nnen,...","breadcrumb":{"@id":"https:\/\/kaizen-blog.org\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kaizen-blog.org\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kaizen-blog.org\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/#primaryimage","url":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/09\/Kaizen-Blog7.webp?fit=905%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/09\/Kaizen-Blog7.webp?fit=905%2C500&ssl=1","width":905,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/kaizen-blog.org\/ein-land-am-wendepunkt-obama-warnt-vor-der-toedlichen-normalisierung-des-politischen-hasses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kaizen-blog.org\/"},{"@type":"ListItem","position":2,"name":"Ein Land am Wendepunkt \u2013 Obama warnt vor der t\u00f6dlichen Normalisierung des politischen Hasses"}]},{"@type":"WebSite","@id":"https:\/\/kaizen-blog.org\/#website","url":"https:\/\/kaizen-blog.org\/","name":"The Kaizen Blog","description":"Investigative Journalism","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kaizen-blog.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/kaizen-blog.org\/#\/schema\/person\/7d3fc7346e2501a389ea3daa48b99ad0","name":"Rainer Hofmann","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","url":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","contentUrl":"\/\/www.gravatar.com\/avatar\/21e5b26d4f12b21206d8094d7aea4ab6?s=96&#038;r=g&#038;d=initials","caption":"Rainer Hofmann"},"sameAs":["https:\/\/kaizen-blog.org"],"url":"https:\/\/kaizen-blog.org\/en\/author\/admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2025\/09\/Kaizen-Blog7.webp?fit=905%2C500&ssl=1","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":30607,"url":"https:\/\/kaizen-blog.org\/en\/die-rede-einer-heuchlerin\/","url_meta":{"origin":15478,"position":0},"title":"The Speech of a Hypocrite","author":"Rainer Hofmann","date":"March 3, 2026","format":false,"excerpt":"Melania Trump stand am Montag auf der Trib\u00fcne des UN-Sicherheitsrats und redete \u00fcber Kinder, \u00fcber Frieden, \u00fcber Hoffnung. Sie stand dort, w\u00e4hrend die Bomben fielen. Das ist nicht Ironie, das ist Gesch\u00e4ft. Das ist Normalit\u00e4t in einer Welt, die l\u00e4ngst aufgeh\u00f6rt hat, sich selbst zu widersprechen. Die First Lady sitzt\u2026","rel":"","context":"In &quot;Daylight&quot;","block_context":{"text":"Daylight","link":"https:\/\/kaizen-blog.org\/en\/category\/daylight\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizennewsday-2026-03-03T022955.188.webp?fit=905%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizennewsday-2026-03-03T022955.188.webp?fit=905%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizennewsday-2026-03-03T022955.188.webp?fit=905%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizennewsday-2026-03-03T022955.188.webp?fit=905%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31224,"url":"https:\/\/kaizen-blog.org\/en\/10-maerz-2026-kurznachrichten\/","url_meta":{"origin":15478,"position":1},"title":"March 10, 2026 \u2013 Short News","author":"TEAM KAIZEN BLOG","date":"March 10, 2026","format":false,"excerpt":"Trump telefoniert mit Putin \u2013 Iran, Ukraine und der \u00d6lmarkt im selben Gespr\u00e4ch! Trump \u00fcber Russland: \u201eWir werden diese Sanktionen aufheben, bis sich die Lage wieder ordnet. Wer wei\u00df, vielleicht m\u00fcssen wir sie gar nicht wieder verh\u00e4ngen.\u201c - (Trump bezieht sich aber nur auf den Zusammenhang der Sanktionen, die den\u2026","rel":"","context":"In &quot;+++ Kaizen News Ticker +++&quot;","block_context":{"text":"+++ Kaizen News Ticker +++","link":"https:\/\/kaizen-blog.org\/en\/category\/ticker\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizenlive-2026-03-10T011434.038.webp?fit=905%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizenlive-2026-03-10T011434.038.webp?fit=905%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizenlive-2026-03-10T011434.038.webp?fit=905%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizenlive-2026-03-10T011434.038.webp?fit=905%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31123,"url":"https:\/\/kaizen-blog.org\/en\/recherchen-belegen-wenn-russisches-oel-georgisch-wird-und-in-der-eu-landet-der-fall-kulevi\/","url_meta":{"origin":15478,"position":2},"title":"Research proves: When Russian oil becomes \"Georgian\" and ends up in the EU - The Kulevi case","author":"Rainer Hofmann","date":"March 8, 2026","format":false,"excerpt":"Im Januar 2026 exportierte Georgien angeblich eigene Erd\u00f6lprodukte im Wert von 56 Millionen Dollar. Ein Anstieg um 3300 Prozent im Vergleich zum Vorjahr. Erd\u00f6lprodukte r\u00fcckten damit auf Platz zwei der georgischen Exportstatistik. Ein Land ohne nennenswerte eigene F\u00f6rderung, ohne gewachsene Raffineriekapazit\u00e4ten \u2013 und pl\u00f6tzlich ein Schwergewicht im \u00d6lgesch\u00e4ft. Die Erkl\u00e4rung\u2026","rel":"","context":"In &quot;NEWS&quot;","block_context":{"text":"NEWS","link":"https:\/\/kaizen-blog.org\/en\/category\/news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizennewsday-2026-03-08T170706.936.webp?fit=905%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizennewsday-2026-03-08T170706.936.webp?fit=905%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizennewsday-2026-03-08T170706.936.webp?fit=905%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizennewsday-2026-03-08T170706.936.webp?fit=905%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31259,"url":"https:\/\/kaizen-blog.org\/en\/warten-auf-den-grossen-krieg-wie-al-qaida-vom-globalen-chaos-profitieren-will-und-wie-moskau-eigene-allianzen-im-schatten-knuepft\/","url_meta":{"origin":15478,"position":3},"title":"Waiting for the Great War - How Al Qaeda Intends to Profit from Global Chaos and How Moscow Is Forging Its Own Alliances in the Shadows","author":"Rainer Hofmann","date":"March 10, 2026","format":false,"excerpt":"Al-Qaida rechnet mit einem dritten Weltkrieg. Und die Organisation plant nicht, am Rand zu stehen. Ein im Januar 2026 ver\u00f6ffentlichtes Papier mit dem Titel \u201eDie Zukunft des Islam im Lichte der gegenw\u00e4rtigen globalen Umbr\u00fcche\u201c, verbreitet \u00fcber arabischsprachige Kan\u00e4le der Al-Qaida auf der Arabischen Halbinsel, beschreibt eine Welt auf dem Weg\u2026","rel":"","context":"In &quot;Kaizen Flashpoint&quot;","block_context":{"text":"Kaizen Flashpoint","link":"https:\/\/kaizen-blog.org\/en\/category\/madness\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/putin-isis.webp?fit=640%2C327&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/putin-isis.webp?fit=640%2C327&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/putin-isis.webp?fit=640%2C327&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":31153,"url":"https:\/\/kaizen-blog.org\/en\/54-kilometer-gegen-den-rest-der-welt\/","url_meta":{"origin":15478,"position":4},"title":"54 Kilometers Against the Rest of the World","author":"Rainer Hofmann","date":"March 9, 2026","format":false,"excerpt":"57 Containerschiffe stecken in der Stra\u00dfe von Hormus fest. Man schreibt das hin und es klingt nach einer Zahl. Es ist mehr als das. Der Tankerverkehr ist um 90 Prozent eingebrochen. Maersk hat neue Buchungen f\u00fcr die gesamte Region ausgesetzt. MSC leitet Ladung in sichere H\u00e4fen um. Container stehen in\u2026","rel":"","context":"In &quot;Iran War&quot;","block_context":{"text":"Iran War","link":"https:\/\/kaizen-blog.org\/en\/category\/investigativ\/iran-war\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizennewsday-2026-03-08T152547.869.jpg?fit=905%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizennewsday-2026-03-08T152547.869.jpg?fit=905%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizennewsday-2026-03-08T152547.869.jpg?fit=905%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/03\/kaizennewsday-2026-03-08T152547.869.jpg?fit=905%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":34807,"url":"https:\/\/kaizen-blog.org\/en\/24-april-2026-kurznachrichten\/","url_meta":{"origin":15478,"position":5},"title":"April 24, 2026 \u2013 Short News","author":"TEAM KAIZEN BLOG","date":"April 24, 2026","format":false,"excerpt":"Papst Leo fordert Gespr\u00e4che statt Krieg \u2013 und verurteilt jede Hinrichtung! Papst Leo XIV sitzt im Flugzeug auf dem R\u00fcckweg aus Afrika und spricht Klartext, ohne laut zu werden. Er fordert die Vereinigten Staaten und Iran auf, wieder miteinander zu reden, nicht irgendwann, sondern jetzt. F\u00fcr ihn ist die entscheidende\u2026","rel":"","context":"In &quot;+++ Kaizen News Ticker +++&quot;","block_context":{"text":"+++ Kaizen News Ticker +++","link":"https:\/\/kaizen-blog.org\/en\/category\/ticker\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/kaizenlive-2026-04-24T005938.002.webp?fit=905%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/kaizenlive-2026-04-24T005938.002.webp?fit=905%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/kaizenlive-2026-04-24T005938.002.webp?fit=905%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/kaizen-blog.org\/wp-content\/uploads\/2026\/04\/kaizenlive-2026-04-24T005938.002.webp?fit=905%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts\/15478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/comments?post=15478"}],"version-history":[{"count":0,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/posts\/15478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/media\/15479"}],"wp:attachment":[{"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/media?parent=15478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/categories?post=15478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kaizen-blog.org\/en\/wp-json\/wp\/v2\/tags?post=15478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}